{"id":9882,"date":"2025-12-10T14:18:40","date_gmt":"2025-12-10T13:18:40","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=9882"},"modified":"2026-03-24T08:55:36","modified_gmt":"2026-03-24T07:55:36","slug":"el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/","title":{"rendered":"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al &#8216;Basurazo de Carrasco&#8217;"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>La portavoz del Grupo Municipal Socialista, Patricia Puerta, se\u00f1ala que los informes jur\u00eddicos \u201cavalan la legalidad de nuestras medidas\u201d, pero el gobierno municipal se limita a justificar en \u201cun problema de fechas\u201d la decisi\u00f3n de bloquear unas iniciativas que beneficiaban a la ciudadan\u00eda<\/em><\/li>\n<\/ul>\n\n\n\n<p>El\u00a0Grupo Municipal Socialista ha acusado a la alcaldesa de Castell\u00f3, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a>, de \u201cpasar de nuevo el rodillo\u201d para sacar adelante las ordenanzas fiscales de PP y Vox de 2026, \u201cunas ordenanzas que vuelven a suponer un duro golpe para los bolsillos de las familias castellonenses y que confirman el impacto econ\u00f3mico del Basurazo de Carrasco\u201d.<\/p>\n\n\n\n<p><a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>, portavoz socialista, se\u00f1ala que \u201clos informes jur\u00eddicos han avalado la legalidad de todas nuestras alegaciones, pero ya hemos podido comprobar la nula disposici\u00f3n del gobierno municipal a llegar a acuerdos con la oposici\u00f3n, lo que supone, no un ataque al Partido Socialista, sino un desprecio absoluto a los vecinos y vecinas, que sufren la incapacidad absoluta de PP y Vox para gestionar la tasa de basuras y el resto de tasas e impuestos municipales\u201d.<\/p>\n\n\n\n<p>Para Puerta, \u201cque la \u00fanica justificaci\u00f3n que nos dan es que, aceptar nuestras iniciativas supondr\u00eda tener que cambiar las ordenanzas fiscales, volver a exponerlas al p\u00fablico y aprobarlas definitivamente en otro pleno, revela el absoluto caos en el que se encuentran, porque PP y Vox son los \u00fanicos culpables de gestionar tarde y mal el calendario\u201d. Los informes jur\u00eddicos, como explica la portavoz socialista, \u201cavalan la legalidad de nuestras propuestas, pero parece ser que tenemos una alcaldesa a la que le molesta que desde la oposici\u00f3n le enmendemos la plana y la dejemos en evidencia\u201d.<\/p>\n\n\n\n<p>El Grupo Municipal Socialista de Castell\u00f3 present\u00f3 la semana pasada sus alegaciones a las Ordenanzas Fiscales de 2026, un documento que pretend\u00eda ampliar las bonificaciones econ\u00f3micas a las familias castellonenses y paliar de forma efectiva \u201cel golpe que va a suponer el Basurazo de Carrasco durante el a\u00f1o que viene tras el varapalo sufrido ya este 2025\u201d. Y entre las medidas del PSPV estaba vincular el pago de la tasa de basuras del PP y Vox al consumo de agua y al n\u00famero de personas que reside en la vivienda, \u201cya que la alcaldesa no ha cumplido, ni cumple, el requisito de la Ley de que tiene que pagar m\u00e1s quien m\u00e1s contamina y tiene que bonificarse m\u00e1s quien m\u00e1s recicla\u201d.<\/p>\n\n\n\n<p>La Ley 7\/2022, de 8 de abril, de Residuos y Suelos Contaminados para una Econom\u00eda Circular, que es la transposici\u00f3n de una normativa europea impulsada en Bruselas por el Partido Popular Europeo, obliga a los municipios a implantar sistemas de pago por generaci\u00f3n real de residuos (PxG). \u201cSin embargo, su implementaci\u00f3n en la ciudad de Castell\u00f3 no es progresiva y ha sido generalizada para la totalidad de los inmuebles, lo que ha provocado la mayor subida de una tasa en la ciudad de Castell\u00f3 y una de las m\u00e1s altas de todo el Estado espa\u00f1ol\u201d.<\/p>\n\n\n\n<p>La propuesta principal del Grupo Municipal Socialista para 2026 pretend\u00eda aplicar criterios diferenciadores a la hora de calcular la tarifa de la tasa de basura, que pasar\u00eda as\u00ed a estar vinculada al consumo de agua de cada inmueble y al n\u00famero de personas que habitan en esa vivienda.<\/p>\n\n\n\n<p>En el apartado de exenciones y bonificaciones, el PSPV de Castell\u00f3 propon\u00eda reforzar las reducciones a las personas arrendatarias de una vivienda, como incluir a las familias numerosas que viven de alquiler en la bonificaci\u00f3n del 60% y, en el apartado de bonificaci\u00f3n a los alquilados que depositen residuos en los ecoparques, incluir a familias monoparentales, monomarentales, en situaci\u00f3n de vulnerabilidad o con grado de dependencia o discapacidad.<\/p>\n\n\n\n<p><strong>Rebaja del IBI y del ICIO<\/strong><\/p>\n\n\n\n<p>Las alegaciones socialistas tambi\u00e9n se centraban en el Impuesto de Bienes Inmuebles (IBI) y en el Impuesto sobre Construcciones, Instalaciones y Obras (ICIO). Respecto al IBI de naturaleza urbana, desde el PSPV se planteaba reducir el tipo aplicable \u201cen un porcentaje equivalente al incremento de la recaudaci\u00f3n motivada por el \u2018Basurazo de Carrasco\u2019, actuando sobre el tipo efectivo para viviendas y locales comerciales\u201d. En relaci\u00f3n al IBI de naturaleza r\u00fastica, la idea era reducir el tipo aplicable en un 2 %, pasando del 0,60 actual al 0, 58%.<\/p>\n\n\n\n<p>Finalmente, para el ICIO, el Partido Socialista apostaba por una bajada del tipo de gravamen en un 13,33%: del 3,00% al 2,60%. Y ello a consecuencia de tener plenamente salvaguardada la legalidad del Plan General de Castell\u00f3, porque esta estabilidad respaldaba sin duda la bajada del ICIO y ayudar as\u00ed al fomento y dinamizaci\u00f3n de la econom\u00eda local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Grupo Municipal Socialista ha acusado a la alcaldesa de Castell\u00f3, Bego\u00f1a Carrasco, de \u201cpasar de nuevo el rodillo\u201d para sacar adelante las ordenanzas fiscales de PP y Vox de 2026, \u201cunas ordenanzas que vuelven a suponer un duro golpe para los bolsillos de las familias castellonenses y que confirman el impacto econ\u00f3mico del Basurazo de &#8230;<\/p>\n","protected":false},"author":48,"featured_media":9883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[1151,733,81,448],"class_list":["post-9882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-basurazo","tag-begona-carrasco","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al &#039;Basurazo de Carrasco&#039; - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al &#039;Basurazo de Carrasco&#039; - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El\u00a0Grupo Municipal Socialista ha acusado a la alcaldesa de Castell\u00f3, Bego\u00f1a Carrasco, de \u201cpasar de nuevo el rodillo\u201d para sacar adelante las ordenanzas fiscales de PP y Vox de 2026, \u201cunas ordenanzas que vuelven a suponer un duro golpe para los bolsillos de las familias castellonenses y que confirman el impacto econ\u00f3mico del Basurazo de ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-10T13:18:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T07:55:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al &#8216;Basurazo de Carrasco&#8217;\",\"datePublished\":\"2025-12-10T13:18:40+00:00\",\"dateModified\":\"2026-03-24T07:55:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/\"},\"wordCount\":801,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg\",\"keywords\":[\"Basurazo\",\"Bego\u00f1a Carrasco\",\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/\",\"name\":\"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al 'Basurazo de Carrasco' - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg\",\"datePublished\":\"2025-12-10T13:18:40+00:00\",\"dateModified\":\"2026-03-24T07:55:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al &#8216;Basurazo de Carrasco&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al 'Basurazo de Carrasco' - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/","og_locale":"es_ES","og_type":"article","og_title":"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al 'Basurazo de Carrasco' - PSPV-PSOE CASTELL\u00d3","og_description":"El\u00a0Grupo Municipal Socialista ha acusado a la alcaldesa de Castell\u00f3, Bego\u00f1a Carrasco, de \u201cpasar de nuevo el rodillo\u201d para sacar adelante las ordenanzas fiscales de PP y Vox de 2026, \u201cunas ordenanzas que vuelven a suponer un duro golpe para los bolsillos de las familias castellonenses y que confirman el impacto econ\u00f3mico del Basurazo de ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-12-10T13:18:40+00:00","article_modified_time":"2026-03-24T07:55:36+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al &#8216;Basurazo de Carrasco&#8217;","datePublished":"2025-12-10T13:18:40+00:00","dateModified":"2026-03-24T07:55:36+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/"},"wordCount":801,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg","keywords":["Basurazo","Bego\u00f1a Carrasco","Patricia Puerta","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/","name":"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al 'Basurazo de Carrasco' - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg","datePublished":"2025-12-10T13:18:40+00:00","dateModified":"2026-03-24T07:55:36+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-pspv-de-castello-frente-al-basurazo-de-carrasco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PP pasa el rodillo y rechaza todas las propuestas del PSPV de Castell\u00f3 frente al &#8216;Basurazo de Carrasco&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251210-El-PP-pasa-el-rodillo-y-rechaza-todas-las-propuestas-del-PSPV-de-Castello-frente-al-Basurazo-de-Carrasco.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=9882"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9882\/revisions"}],"predecessor-version":[{"id":9885,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9882\/revisions\/9885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/9883"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=9882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=9882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=9882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}