{"id":9776,"date":"2025-11-28T15:01:00","date_gmt":"2025-11-28T14:01:00","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=9776"},"modified":"2025-11-29T11:23:09","modified_gmt":"2025-11-29T10:23:09","slug":"el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/","title":{"rendered":"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d&#8217;euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d&#8217;embelliment"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>El regidor socialista Jorge Ribes qualifica de \u201ccovard\u201d el projecte de ZBE impulsat per Bego\u00f1a Carrasco i adverteix que un incompliment d&#8217;aquest programa va en contra del finan\u00e7ament rebut de la Uni\u00f3 Europea<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Ribes qualifica de \u201cirresponsable\u201d al PP per donar suport a una proposta de Vox, vetada pel PSPV i Comprom\u00eds, per a derogar les zones de baixes emissions<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"El PSPV de Castell\u00f3 acusa a PP y Vox de poner en riesgo millones de euros tras convertir la Zona de\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/_8Ea2z6j7SA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>La \u201cirresponsabilitat\u201d de <a href=\"https:\/\/agrupacionespsoe.es\/castello\/va\/tag\/begona-carrasco-va\/\">Bego\u00f1a Carrasco<\/a> pot portar a l&#8217;Ajuntament de Castell\u00f3 a perdre milions d&#8217;euros de la Uni\u00f3 Europea \u201cper haver convertit la Zona de Baixes Emissions en un mer pla d&#8217;embelliment de la ciutat\u201d. L&#8217;advertiment la va realitzar ahir en el ple el regidor socialista <a href=\"https:\/\/agrupacionespsoe.es\/castello\/va\/tag\/jorge-ribes-va\/\">Jorge Ribes<\/a>, qui va qualificar de \u201ccovard\u201d el projecte de ZBE aprovat ahir amb els vots del PP i Vox, \u201cals qui cada vegada costa m\u00e9s distingir amb la seua negacionisme clim\u00e0tic\u201d.<\/p>\n\n\n\n<p>Ribes ha recordat que Vox va presentar recentment en Les Corts una Proposici\u00f3 No de Llei perqu\u00e8 s&#8217;anul\u00b7len les zones de baixes emissions en la Comunitat Valenciana, al que va sumar una proposta de declaraci\u00f3 institucional, per al ple celebrat ahir, demanant la derogaci\u00f3 de lleis i l&#8217;anul\u00b7laci\u00f3 de la ZBE de Castell\u00f3. \u201cEl greu, al marge de Vox, \u00e9s que el Partit Popular, que la senyora Bego\u00f1a Carrasco, avalara en la Junta de Portaveus del passat dilluns aquesta proposta de la ultradreta, una absoluta insensatesa perqu\u00e8 estem posant en risc la pr\u00f2pia estabilitat pressupost\u00e0ria de l&#8217;ajuntament\u201d.<\/p>\n\n\n\n<p>Per a l&#8217;edil socialista, \u201cestem davant un fet perill\u00f3s\u201d. Primer, \u201cper aquest intent d&#8217;anar en contra dels preceptes ambientals d&#8217;Europa, on per cert governa la dreta, i segon per manipular el sentit de la ZBE de Castell\u00f3 i aprovar ahir un projecte amputat\u201d. A m\u00e9s, \u201cconstatem el rid\u00edcul de Vox, que d&#8217;una banda vol acabar amb les zones de baixes emissions, per\u00f2 per un altre dona suport a la ZBE de Carrasco, no siga que s&#8217;enfade i posen en risc els 60.000 \u20ac que cobren a l&#8217;any al govern municipal\u201d.<\/p>\n\n\n\n<p>Jorge Ribes, en aquest l\u00ednia, adverteix que la proposta de l&#8217;equip de govern aprovada ahir per PP i Vox \u201cobri les portes de nou a una ciutat col\u00b7lapsada pels cotxes en el centre i nega l&#8217;evid\u00e8ncia cient\u00edfica, i tamb\u00e9 emp\u00edrica, que on no circulen cotxes amb assidu\u00eftat millora el comer\u00e7, es redueixen els nivells de soroll i contaminaci\u00f3, augmenta l&#8217;accessibilitat i, per descomptat, millora la qualitat de vida de la ciutadania\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u201cirresponsabilitat\u201d de Bego\u00f1a Carrasco pot portar a l&#8217;Ajuntament de Castell\u00f3 a perdre milions d&#8217;euros de la Uni\u00f3 Europea \u201cper haver convertit la Zona de Baixes Emissions en un mer pla d&#8217;embelliment de la ciutat\u201d. L&#8217;advertiment la va realitzar ahir en el ple el regidor socialista Jorge Ribes, qui va qualificar de \u201ccovard\u201d el projecte &#8230;<\/p>\n","protected":false},"author":48,"featured_media":9773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[741,93,446],"class_list":["post-9776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms-va","tag-begona-carrasco-va","tag-jorge-ribes-va","tag-todos-va"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d&#039;euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d&#039;embelliment - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d&#039;euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d&#039;embelliment - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"La \u201cirresponsabilitat\u201d de Bego\u00f1a Carrasco pot portar a l&#8217;Ajuntament de Castell\u00f3 a perdre milions d&#8217;euros de la Uni\u00f3 Europea \u201cper haver convertit la Zona de Baixes Emissions en un mer pla d&#8217;embelliment de la ciutat\u201d. L&#8217;advertiment la va realitzar ahir en el ple el regidor socialista Jorge Ribes, qui va qualificar de \u201ccovard\u201d el projecte ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-28T14:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T10:23:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d&#8217;euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d&#8217;embelliment\",\"datePublished\":\"2025-11-28T14:01:00+00:00\",\"dateModified\":\"2025-11-29T10:23:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/\"},\"wordCount\":449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg\",\"keywords\":[\"Bego\u00f1a Carrasco\",\"Jorge Ribes\",\"Todos\"],\"articleSection\":[\"Grup Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/\",\"name\":\"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d'euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d'embelliment - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg\",\"datePublished\":\"2025-11-28T14:01:00+00:00\",\"dateModified\":\"2025-11-29T10:23:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d&#8217;euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d&#8217;embelliment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d'euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d'embelliment - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d'euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d'embelliment - PSPV-PSOE CASTELL\u00d3","og_description":"La \u201cirresponsabilitat\u201d de Bego\u00f1a Carrasco pot portar a l&#8217;Ajuntament de Castell\u00f3 a perdre milions d&#8217;euros de la Uni\u00f3 Europea \u201cper haver convertit la Zona de Baixes Emissions en un mer pla d&#8217;embelliment de la ciutat\u201d. L&#8217;advertiment la va realitzar ahir en el ple el regidor socialista Jorge Ribes, qui va qualificar de \u201ccovard\u201d el projecte ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-11-28T14:01:00+00:00","article_modified_time":"2025-11-29T10:23:09+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d&#8217;euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d&#8217;embelliment","datePublished":"2025-11-28T14:01:00+00:00","dateModified":"2025-11-29T10:23:09+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/"},"wordCount":449,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg","keywords":["Bego\u00f1a Carrasco","Jorge Ribes","Todos"],"articleSection":["Grup Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/","url":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/","name":"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d'euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d'embelliment - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg","datePublished":"2025-11-28T14:01:00+00:00","dateModified":"2025-11-29T10:23:09+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-de-castello-acusa-pp-i-vox-de-posar-en-risc-milions-deuros-despres-de-convertir-la-zona-de-baixes-emissions-en-un-mer-pla-dembelliment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV de Castell\u00f3 acusa PP i Vox de posar en risc milions d&#8217;euros despr\u00e9s de convertir la Zona de Baixes Emissions en un mer pla d&#8217;embelliment"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/11\/20251128-El-PSPV-de-Castello-acusa-a-PP-y-Vox-de-poner-en-riesgo-millones-de-euros-tras-convertir-la-Zona-de-Bajas-Emisiones-en-un-mero-plan-de-embellecimiento.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=9776"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9776\/revisions"}],"predecessor-version":[{"id":9778,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9776\/revisions\/9778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/9773"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=9776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=9776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=9776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}