{"id":9292,"date":"2025-10-27T14:53:16","date_gmt":"2025-10-27T13:53:16","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=9292"},"modified":"2025-10-27T14:53:18","modified_gmt":"2025-10-27T13:53:18","slug":"el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/","title":{"rendered":"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>La concejala socialista Anunciaci\u00f3n L\u00e1inez recuerda que \u201chemos denunciado el abandono de la zona desde el pasado mes de agosto, pero el ayuntamiento mira a otro lado al no pedir actuaciones al Coto Arrocero\u201d<\/em><\/li>\n<\/ul>\n\n\n\n<p>Meses de abandono y sin ning\u00fan inter\u00e9s por parte del Ayuntamiento de Castell\u00f3 para adecentar la acequia del Cam\u00ed la Ratlla. Esta es la situaci\u00f3n que han trasladado al grupo Municipal Socialista los vecinos y vecinas de la zona, \u201cque ven a diario la acumulaci\u00f3n de basura en la acequia, el enorme peligro en el caso de lluvias intensas y, en la actualidad, la enorme plaga de mosquitos que les afecta\u201d.<\/p>\n\n\n\n<p><a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/anun-lainez\/\">Anunciaci\u00f3n L\u00e1inez<\/a>, concejala socialista, ha recordado que \u201cya denunciamos el estado de la acequia el pasado mes de agosto, con una imagen de abandono absoluto, con el cauce lleno de basura y maleza y el taponamiento de algunas de sus canalizaciones\u201d. Desde el PSPV \u201ctrasladamos esta situaci\u00f3n al equipo de gobierno, pero se limitaron a decir que no era responsabilidad suya y que el que ten\u00eda que actuar era el Coto Arrocero\u201d.<\/p>\n\n\n\n<p>La edil socialista, al respecto, ha lamentado que \u201cel \u00fanico paso dado por el gobierno de <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a> sea quitarse todo tipo de responsabilidad, cuando lo que ten\u00eda que hacer desde el primer minuto era interesarse por la situaci\u00f3n y, en su caso, trasladar al Coto Arrocero el estado de la acequia, sobre todo cuando existe un convenio con esta entidad por el que se aportan 175.000 euros\u201d.<\/p>\n\n\n\n<p>Por tal motivo, desde el grupo Municipal Socialista se ha realizado un nuevo ruego en el seno de las comisiones municipales de hoy lunes, \u201cdonde hemos solicitado copia del escrito que, supuestamente, se traslad\u00f3 al Coto Arrocero para la limpieza de la acequia del Cam\u00ed La Ratlla y que, seg\u00fan la respuesta del equipo de gobierno en la comisi\u00f3n del pasado 6 de octubre, se hab\u00eda ejecutado\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meses de abandono y sin ning\u00fan inter\u00e9s por parte del Ayuntamiento de Castell\u00f3 para adecentar la acequia del Cam\u00ed la Ratlla. Esta es la situaci\u00f3n que han trasladado al grupo Municipal Socialista los vecinos y vecinas de la zona, \u201cque ven a diario la acumulaci\u00f3n de basura en la acequia, el enorme peligro en el &#8230;<\/p>\n","protected":false},"author":48,"featured_media":9293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[95,733,448],"class_list":["post-9292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-anun-lainez","tag-begona-carrasco","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"Meses de abandono y sin ning\u00fan inter\u00e9s por parte del Ayuntamiento de Castell\u00f3 para adecentar la acequia del Cam\u00ed la Ratlla. Esta es la situaci\u00f3n que han trasladado al grupo Municipal Socialista los vecinos y vecinas de la zona, \u201cque ven a diario la acumulaci\u00f3n de basura en la acequia, el enorme peligro en el ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T13:53:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T13:53:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos\",\"datePublished\":\"2025-10-27T13:53:16+00:00\",\"dateModified\":\"2025-10-27T13:53:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg\",\"keywords\":[\"Anun L\u00e1inez\",\"Bego\u00f1a Carrasco\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/\",\"name\":\"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg\",\"datePublished\":\"2025-10-27T13:53:16+00:00\",\"dateModified\":\"2025-10-27T13:53:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg\",\"width\":1536,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/","og_locale":"es_ES","og_type":"article","og_title":"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos - PSPV-PSOE CASTELL\u00d3","og_description":"Meses de abandono y sin ning\u00fan inter\u00e9s por parte del Ayuntamiento de Castell\u00f3 para adecentar la acequia del Cam\u00ed la Ratlla. Esta es la situaci\u00f3n que han trasladado al grupo Municipal Socialista los vecinos y vecinas de la zona, \u201cque ven a diario la acumulaci\u00f3n de basura en la acequia, el enorme peligro en el ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-10-27T13:53:16+00:00","article_modified_time":"2025-10-27T13:53:18+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos","datePublished":"2025-10-27T13:53:16+00:00","dateModified":"2025-10-27T13:53:18+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg","keywords":["Anun L\u00e1inez","Bego\u00f1a Carrasco","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/","name":"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg","datePublished":"2025-10-27T13:53:16+00:00","dateModified":"2025-10-27T13:53:18+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg","width":1536,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-gobierno-de-carrasco-abandona-a-los-vecinos-y-vecinas-del-cami-la-ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El gobierno de Carrasco abandona a los vecinos y vecinas del Cam\u00ed la Ratlla al seguir sin limpiar la acequia y no combatir la plaga de mosquitos"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251027-El-gobierno-de-Carrasco-abandona-a-los-vecinos-y-vecinas-del-Cami-la-Ratlla-al-seguir-sin-limpiar-la-acequia-y-no-combatir-la-plaga-de-mosquitos.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=9292"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9292\/revisions"}],"predecessor-version":[{"id":9295,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9292\/revisions\/9295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/9293"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=9292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=9292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=9292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}