{"id":9261,"date":"2025-10-24T13:41:27","date_gmt":"2025-10-24T11:41:27","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=9261"},"modified":"2025-10-24T13:42:37","modified_gmt":"2025-10-24T11:42:37","slug":"el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/","title":{"rendered":"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>El Grupo Municipal Socialista solicita celebrar el homenaje el pr\u00f3ximo mi\u00e9rcoles, a las 20.11 horas, coincidiendo con el env\u00edo de la alerta a los m\u00f3viles en la zona afectada<\/em><\/li>\n<\/ul>\n\n\n\n<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado este mediod\u00eda una solicitud dirigida a la alcaldesa, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a>, para que convoque cinco minutos de silencio el pr\u00f3ximo mi\u00e9rcoles 29 de octubre, coincidiendo con el primer aniversario de la dana que afect\u00f3, sobre todo, a la provincia de Valencia.<\/p>\n\n\n\n<p>La portavoz socialista, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>, firma la solicitud que recuerda que en esta fecha se cumplir\u00e1 un a\u00f1o de la tragedia de la dana en la que perdieron la vida 229 personas, \u201cuna cat\u00e1strofe que sigue presente en la memoria de toda la ciudadan\u00eda\u201d. Por ello, insta a la primera edil a convocar el homenaje a las 20.11 horas, coincidiendo as\u00ed con el env\u00edo de la alerta a los tel\u00e9fonos m\u00f3viles en la zona afectada.<\/p>\n\n\n\n<p>El Grupo Municipal Socialista solicita a la primera edil la celebraci\u00f3n de este sencillo acto, abierto a la corporaci\u00f3n y la ciudadan\u00eda en general, en la puerta del edificio consistorial como recuerdo a las v\u00edctimas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado este mediod\u00eda una solicitud dirigida a la alcaldesa, Bego\u00f1a Carrasco, para que convoque cinco minutos de silencio el pr\u00f3ximo mi\u00e9rcoles 29 de octubre, coincidiendo con el primer aniversario de la dana que afect\u00f3, sobre todo, a la provincia de Valencia. La portavoz socialista, Patricia Puerta, &#8230;<\/p>\n","protected":false},"author":48,"featured_media":9262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[733,81,448],"class_list":["post-9261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-begona-carrasco","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado este mediod\u00eda una solicitud dirigida a la alcaldesa, Bego\u00f1a Carrasco, para que convoque cinco minutos de silencio el pr\u00f3ximo mi\u00e9rcoles 29 de octubre, coincidiendo con el primer aniversario de la dana que afect\u00f3, sobre todo, a la provincia de Valencia. La portavoz socialista, Patricia Puerta, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-24T11:41:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T11:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana\",\"datePublished\":\"2025-10-24T11:41:27+00:00\",\"dateModified\":\"2025-10-24T11:42:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/\"},\"wordCount\":223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg\",\"keywords\":[\"Bego\u00f1a Carrasco\",\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/\",\"name\":\"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg\",\"datePublished\":\"2025-10-24T11:41:27+00:00\",\"dateModified\":\"2025-10-24T11:42:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana - PSPV-PSOE CASTELL\u00d3","og_description":"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado este mediod\u00eda una solicitud dirigida a la alcaldesa, Bego\u00f1a Carrasco, para que convoque cinco minutos de silencio el pr\u00f3ximo mi\u00e9rcoles 29 de octubre, coincidiendo con el primer aniversario de la dana que afect\u00f3, sobre todo, a la provincia de Valencia. La portavoz socialista, Patricia Puerta, ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-10-24T11:41:27+00:00","article_modified_time":"2025-10-24T11:42:37+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana","datePublished":"2025-10-24T11:41:27+00:00","dateModified":"2025-10-24T11:42:37+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/"},"wordCount":223,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg","keywords":["Bego\u00f1a Carrasco","Patricia Puerta","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/","name":"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg","datePublished":"2025-10-24T11:41:27+00:00","dateModified":"2025-10-24T11:42:37+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-a-la-alcaldesa-de-castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV pide a la alcaldesa de Castell\u00f3 que convoque cinco minutos de silencio en el aniversario de la dana"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251024-El-PSPV-pide-a-la-alcaldesa-de-Castello-que-convoque-cinco-minutos-de-silencio-en-el-aniversario-de-la-dana.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=9261"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9261\/revisions"}],"predecessor-version":[{"id":9267,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9261\/revisions\/9267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/9262"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=9261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=9261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=9261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}