{"id":9250,"date":"2025-10-23T13:36:17","date_gmt":"2025-10-23T11:36:17","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=9250"},"modified":"2025-10-23T13:44:32","modified_gmt":"2025-10-23T11:44:32","slug":"el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/","title":{"rendered":"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em><em>El Grupo Municipal Socialista considera que el cambio de denominaci\u00f3n \u201ces una propuesta sectaria e ideol\u00f3gica de Vox que ha aceptado una alcaldesa, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a>, cada vez m\u00e1s escorada a la derecha\u201d<\/em><\/em><\/li>\n<\/ul>\n\n\n\n<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha presentado una moci\u00f3n, para su debate y aprobaci\u00f3n en el pleno ordinario del pr\u00f3ximo 30 de octubre, para reclamar al gobierno municipal que&nbsp;mantenga el nombre de \u2018Pa\u00eds Valenci\u00e0\u201d en la plaza situada al final de la calle Trinidad de la ciudad. La propuesta, adem\u00e1s, recoge que se utilice la nomenclatura de \u20189 de octubre\u2019 para otro espacio del callejero de la ciudad\u00bb.<\/p>\n\n\n\n<p>El Partido Popular y VOX aprobaron en Junta de Gobierno Local, el pasado 8 de octubre, el cambio de nombre de la plaza del \u201cPa\u00eds Valenci\u00e0\u201d al de plaza \u20189 d\u2019Octubre\u2019, una propuesta \u201cabsolutamente ideol\u00f3gica que no ha contado ni con el consenso de todos los grupos pol\u00edticos ni, por supuesto, con los vecinos y vecinas de la zona\u201d, se\u00f1ala <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>, portavoz socialista.<\/p>\n\n\n\n<p>El t\u00e9rmino \u2018Pa\u00eds Valenci\u00e0\u2019 es utilizado y reconocido para referirse al conjunto de los territorios del antiguo Reino de Val\u00e8ncia desde los or\u00edgenes del valencianismo pol\u00edtico, mucho antes de la denominaci\u00f3n de \u201cComunitat Valenciana\u201d en el estatuto de autonom\u00eda de 1982. Fue, adem\u00e1s, el utilizado en los primeros a\u00f1os de transici\u00f3n a la democracia por parte de la incipiente administraci\u00f3n auton\u00f3mica -el r\u00e9gimen preauton\u00f3mico se denominaba Consell del Pa\u00eds Valenci\u00e0- y as\u00ed queda aclarado en el pre\u00e1mbulo del vigente estatuto de autonom\u00eda: \u2018<em>Aprobada la Constituci\u00f3n Espa\u00f1ola fue, en su marco, donde la tradici\u00f3n valenciana proveniente del hist\u00f3rico Reino de Val\u00e8ncia se encontr\u00f3 con la concepci\u00f3n moderna del Pa\u00eds Valenci\u00e0 y dio origen a la autonom\u00eda valenciana\u2019<\/em>.<\/p>\n\n\n\n<p>Adem\u00e1s se trata de un t\u00e9rmino socialmente aceptado por la ciudadan\u00eda de Castell\u00f3, por lo que el nombre original de la plaza \u201cresponde a una parte de nuestra historia, cultura y sentir como pueblo\u201d. Para la portavoz socialista, \u201cel cambio de nominaci\u00f3n es exclusivamente una propuesta sectaria e ideol\u00f3gica de VOX, avalada y aceptada por un PP cada vez m\u00e1s escorado a la derecha, un partido que niega as\u00ed nuestro pasado como pueblo con autonom\u00eda y trayectoria pol\u00edticas propias\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha presentado una moci\u00f3n, para su debate y aprobaci\u00f3n en el pleno ordinario del pr\u00f3ximo 30 de octubre, para reclamar al gobierno municipal que&nbsp;mantenga el nombre de \u2018Pa\u00eds Valenci\u00e0\u201d en la plaza situada al final de la calle Trinidad de la ciudad. La propuesta, adem\u00e1s, recoge que &#8230;<\/p>\n","protected":false},"author":48,"featured_media":7895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[733,81,448],"class_list":["post-9250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-begona-carrasco","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019 - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019 - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha presentado una moci\u00f3n, para su debate y aprobaci\u00f3n en el pleno ordinario del pr\u00f3ximo 30 de octubre, para reclamar al gobierno municipal que&nbsp;mantenga el nombre de \u2018Pa\u00eds Valenci\u00e0\u201d en la plaza situada al final de la calle Trinidad de la ciudad. La propuesta, adem\u00e1s, recoge que ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-23T11:36:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T11:44:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019\",\"datePublished\":\"2025-10-23T11:36:17+00:00\",\"dateModified\":\"2025-10-23T11:44:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/\"},\"wordCount\":425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg\",\"keywords\":[\"Bego\u00f1a Carrasco\",\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/\",\"name\":\"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019 - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg\",\"datePublished\":\"2025-10-23T11:36:17+00:00\",\"dateModified\":\"2025-10-23T11:44:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019 - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019 - PSPV-PSOE CASTELL\u00d3","og_description":"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha presentado una moci\u00f3n, para su debate y aprobaci\u00f3n en el pleno ordinario del pr\u00f3ximo 30 de octubre, para reclamar al gobierno municipal que&nbsp;mantenga el nombre de \u2018Pa\u00eds Valenci\u00e0\u201d en la plaza situada al final de la calle Trinidad de la ciudad. La propuesta, adem\u00e1s, recoge que ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-10-23T11:36:17+00:00","article_modified_time":"2025-10-23T11:44:32+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019","datePublished":"2025-10-23T11:36:17+00:00","dateModified":"2025-10-23T11:44:32+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/"},"wordCount":425,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg","keywords":["Bego\u00f1a Carrasco","Patricia Puerta","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/","name":"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019 - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg","datePublished":"2025-10-23T11:36:17+00:00","dateModified":"2025-10-23T11:44:32+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-presenta-una-mocion-para-mantener-el-nombre-de-la-plaza-pais-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV de Castell\u00f3 presenta una moci\u00f3n para mantener el nombre de la plaza \u2018Pa\u00eds Valenci\u00e0\u2019"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250508-Begona-Carrasco-vuelve-a-hacer-el-ridiculo-al-fracasar-otro-ano-tras-incumplir-su-promesa-de-recuperar-la-bandera-azul-de-la-playa-Serradal-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=9250"}],"version-history":[{"count":3,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9250\/revisions"}],"predecessor-version":[{"id":9256,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9250\/revisions\/9256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/7895"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=9250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=9250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=9250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}