{"id":9121,"date":"2025-10-14T18:21:04","date_gmt":"2025-10-14T16:21:04","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=9121"},"modified":"2025-10-14T18:21:05","modified_gmt":"2025-10-14T16:21:05","slug":"el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/","title":{"rendered":"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>Jos\u00e9 Luis L\u00f3pez, portavoz adjunto del Grupo Municipal Socialista en Castell\u00f3,\u00a0recuerda\u00a0que en los anteriores mandatos del PSPV se destinaron m\u00e1s de 10 millones de euros a infraestructuras hidr\u00e1ulicas,\u00a0como el encauzamiento del Barranco del Sol,\u00a0que han evitado inundaciones y da\u00f1os mayores<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"El PSPV destaca las inversiones de los gobiernos progresistas en infraestructuras hidr\u00e1ulicas de Cas\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/dKx-R6gn57g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Los anteriores gobiernos progresistas\u00a0liderados\u00a0por el PSPV\u00a0en Castell\u00f3\u00a0destinaron m\u00e1s de 10 millones de euros a infraestructuras hidr\u00e1ulicas,\u00a0inversiones\u00a0clave para evitar\u00a0inundaciones y da\u00f1os mayores\u00a0en la capital de la Plana.\u00a0As\u00ed lo destaca el portavoz adjunto del Grupo Municipal Socialista, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/jose-luis-lopez\/\">Jos\u00e9 Luis L\u00f3pez<\/a>, quien se\u00f1ala que esta apuesta decidida\u00a0del Acord de Fadrell y del Pacte del Grau\u00a0permiti\u00f3\u00a0mejorar el drenaje urbano, prevenir inundaciones y modernizar la red pluvial de la ciudad.<\/p>\n\n\n\n<p>Estas actuaciones,&nbsp;como destaca L\u00f3pez,&nbsp;\u201cse planificaron con una visi\u00f3n de ciudad sostenible, preparada para hacer frente forma m\u00e1s efectiva&nbsp;a los efectos del cambio clim\u00e1tico y a los episodios de lluvias torrenciales, que cada vez son m\u00e1s frecuentes en la provincia\u201d.&nbsp;En este sentido, el portavoz adjunto socialista reclama al actual gobierno del PP y VOX \u201cque mantenga el compromiso inversor para garantizar la seguridad de la ciudadan\u00eda,&nbsp;pese a que ya sabemos qu\u00e9 opina el gobierno municipal del cambio clim\u00e1tico\u201d.<\/p>\n\n\n\n<p>Entre las principales inversiones&nbsp;de los gobiernos de progreso&nbsp;destaca la obra de canalizaci\u00f3n y encauzamiento del Barranco del Sol, con un presupuesto de m\u00e1s de 2,5 millones de euros.&nbsp;Este proyecto permiti\u00f3 ampliar y modernizar el cauce del barranco para mejorar su capacidad de desag\u00fce,&nbsp;adem\u00e1s de proteger las viviendas del Barrio de San Agust\u00edn y San Marcos, que habitualmente quedaban afectadas por inundaciones.<\/p>\n\n\n\n<p>Para Jos\u00e9 Luis L\u00f3pez, \u201ces clave \u201cintegrar la actuaci\u00f3n en el entorno urbano con criterios medioambientales y de sostenibilidad.\u201d,&nbsp;algo que representa a la perfecci\u00f3n el encauzamiento del Barranco del Sol\u201d.&nbsp;La reciente&nbsp;dana&nbsp;que ha afectado a la provincia de Castell\u00f3 ha sido,&nbsp;a juicio del portavoz adjunto socialista,&nbsp;\u201cuna&nbsp;buena&nbsp;prueba para&nbsp;ver el estado de&nbsp;esta&nbsp;infraestructura hidr\u00e1ulica,&nbsp;pues ha funcionado&nbsp;con total eficacia, canalizando correctamente el agua y evitando los da\u00f1os y desbordamientos que en otros tiempos eran habituales en la zona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los anteriores gobiernos progresistas\u00a0liderados\u00a0por el PSPV\u00a0en Castell\u00f3\u00a0destinaron m\u00e1s de 10 millones de euros a infraestructuras hidr\u00e1ulicas,\u00a0inversiones\u00a0clave para evitar\u00a0inundaciones y da\u00f1os mayores\u00a0en la capital de la Plana.\u00a0As\u00ed lo destaca el portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, quien se\u00f1ala que esta apuesta decidida\u00a0del Acord de Fadrell y del Pacte del Grau\u00a0permiti\u00f3\u00a0mejorar el drenaje urbano, &#8230;<\/p>\n","protected":false},"author":48,"featured_media":9123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[85,448],"class_list":["post-9121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-jose-luis-lopez","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"Los anteriores gobiernos progresistas\u00a0liderados\u00a0por el PSPV\u00a0en Castell\u00f3\u00a0destinaron m\u00e1s de 10 millones de euros a infraestructuras hidr\u00e1ulicas,\u00a0inversiones\u00a0clave para evitar\u00a0inundaciones y da\u00f1os mayores\u00a0en la capital de la Plana.\u00a0As\u00ed lo destaca el portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, quien se\u00f1ala que esta apuesta decidida\u00a0del Acord de Fadrell y del Pacte del Grau\u00a0permiti\u00f3\u00a0mejorar el drenaje urbano, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T16:21:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T16:21:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana\",\"datePublished\":\"2025-10-14T16:21:04+00:00\",\"dateModified\":\"2025-10-14T16:21:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg\",\"keywords\":[\"Jos\u00e9 Luis L\u00f3pez\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/\",\"name\":\"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg\",\"datePublished\":\"2025-10-14T16:21:04+00:00\",\"dateModified\":\"2025-10-14T16:21:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana - PSPV-PSOE CASTELL\u00d3","og_description":"Los anteriores gobiernos progresistas\u00a0liderados\u00a0por el PSPV\u00a0en Castell\u00f3\u00a0destinaron m\u00e1s de 10 millones de euros a infraestructuras hidr\u00e1ulicas,\u00a0inversiones\u00a0clave para evitar\u00a0inundaciones y da\u00f1os mayores\u00a0en la capital de la Plana.\u00a0As\u00ed lo destaca el portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, quien se\u00f1ala que esta apuesta decidida\u00a0del Acord de Fadrell y del Pacte del Grau\u00a0permiti\u00f3\u00a0mejorar el drenaje urbano, ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-10-14T16:21:04+00:00","article_modified_time":"2025-10-14T16:21:05+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana","datePublished":"2025-10-14T16:21:04+00:00","dateModified":"2025-10-14T16:21:05+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg","keywords":["Jos\u00e9 Luis L\u00f3pez","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/","name":"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg","datePublished":"2025-10-14T16:21:04+00:00","dateModified":"2025-10-14T16:21:05+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-castello-para-hacer-frente-a-los-efectos-de-la-dana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV destaca las inversiones de los gobiernos progresistas\u00a0en infraestructuras hidr\u00e1ulicas de\u00a0Castell\u00f3\u00a0para hacer\u00a0frente a\u00a0los efectos de la dana"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/10\/20251014-El-PSPV-destaca-las-inversiones-de-los-gobiernos-progresistas-en-infraestructuras-hidraulicas-de-Castello-para-hacer-frente-a-los-efectos-de-la-dana.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=9121"}],"version-history":[{"count":3,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9121\/revisions"}],"predecessor-version":[{"id":9125,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/9121\/revisions\/9125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/9123"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=9121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=9121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=9121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}