{"id":8891,"date":"2025-09-19T12:41:12","date_gmt":"2025-09-19T10:41:12","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=8891"},"modified":"2025-09-19T12:41:58","modified_gmt":"2025-09-19T10:41:58","slug":"el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/","title":{"rendered":"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>Patricia Puerta, portavoz del Grupo Municipal Socialista, pide a Bego\u00f1a Carrasco que \u201cabandone las falsas promesas que ha realizado estos dos primeros a\u00f1os\u201d y ponga en marcha una mesa de trabajo municipal \u201cpara impulsar el acceso a una vivienda digna y asequible para las y los castellonenses\u201d<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-video\"><video autoplay controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion.mp4\"><\/video><\/figure>\n\n\n\n<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado hoy de manera oficial el Pacto por la Vivienda anunciado ayer, en el transcurso del debate del Estado de la Ciudad, por la portavoz del PSPV-PSOE, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>. El Partido Socialista anima al Partido Popular a \u201csituar de forma real el derecho a una vivienda digna en el centro de las pol\u00edticas p\u00fablicas del consistorio\u201d, dejando atr\u00e1s dos a\u00f1os \u201cde falsas promesas en un tema que ha de ser una causa com\u00fan\u201d.<\/p>\n\n\n\n<p>La propuesta del PSPV-PSOE, entregada en mano ayer en la sesi\u00f3n plenaria a la alcaldesa, recoge siete ejes prioritarios: aplicar de forma efectiva la Ley Estatal de Vivienda, con especial atenci\u00f3n a la declaraci\u00f3n de zonas tensionadas; crear una mesa municipal de trabajo; activar un plan municipal de ayudas al alquiler social, destinado a personas j\u00f3venes, familias monoparentales y monomarentales, a personas mayores con bajos ingresos y a unidades de convivencia en situaci\u00f3n de vulnerabilidad habitacional; fomentar el alquiler asequible de viviendas vac\u00edas con incentivos a peque\u00f1os propietarios; priorizar la promoci\u00f3n de vivienda p\u00fablica de alquiler asequible; crear un parque municipal de viviendas de alquiler asequible y, finalmente, acordar la suspensi\u00f3n temporal de nuevas licencias de uso tur\u00edstico hasta que se consens\u00fae y apruebe un modelo municipal de alojamiento tur\u00edstico\u201d.<\/p>\n\n\n\n<p>Patricia Puerta pide que Carrasco \u201cdeje atr\u00e1s de una vez sus anuncios vac\u00edos\u201d porque hasta la fecha \u201cya nos ha demostrado que la vivienda no es su prioridad\u201d. \u201cQue ayer la alcaldesa anunciase como proyecto estrella para 2026 que activar\u00e1 un plan de alquiler para personas j\u00f3venes no es ninguna novedad, porque ya aparec\u00eda en las cuentas de 2025 con una partida de apenas 9.000 euros\u201d. Para Patricia Puerta, \u201cla novedad ser\u00eda que cumpliesen sus promesas\u201d.<\/p>\n\n\n\n<p>Pese a todo, desde el PSPV-PSOE se tiende la mano a <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a> para que, dentro del debate pol\u00edtico que tiene que haber en una instituci\u00f3n, \u201cpodamos trabajar de manera conjunta en uno de los grandes problemas que tiene la sociedad actual, que lo que nos reclama a los representantes municipales es que trabajemos en propuestas que den soluci\u00f3n al acceso a una vivienda digna y asequible\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado hoy de manera oficial el Pacto por la Vivienda anunciado ayer, en el transcurso del debate del Estado de la Ciudad, por la portavoz del PSPV-PSOE, Patricia Puerta. El Partido Socialista anima al Partido Popular a \u201csituar de forma real el derecho a una vivienda &#8230;<\/p>\n","protected":false},"author":48,"featured_media":8894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[733,81,448],"class_list":["post-8891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-begona-carrasco","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado hoy de manera oficial el Pacto por la Vivienda anunciado ayer, en el transcurso del debate del Estado de la Ciudad, por la portavoz del PSPV-PSOE, Patricia Puerta. El Partido Socialista anima al Partido Popular a \u201csituar de forma real el derecho a una vivienda ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-19T10:41:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T10:41:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n\",\"datePublished\":\"2025-09-19T10:41:12+00:00\",\"dateModified\":\"2025-09-19T10:41:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg\",\"keywords\":[\"Bego\u00f1a Carrasco\",\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/\",\"name\":\"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg\",\"datePublished\":\"2025-09-19T10:41:12+00:00\",\"dateModified\":\"2025-09-19T10:41:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n - PSPV-PSOE CASTELL\u00d3","og_description":"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado hoy de manera oficial el Pacto por la Vivienda anunciado ayer, en el transcurso del debate del Estado de la Ciudad, por la portavoz del PSPV-PSOE, Patricia Puerta. El Partido Socialista anima al Partido Popular a \u201csituar de forma real el derecho a una vivienda ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-09-19T10:41:12+00:00","article_modified_time":"2025-09-19T10:41:58+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n","datePublished":"2025-09-19T10:41:12+00:00","dateModified":"2025-09-19T10:41:58+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg","keywords":["Bego\u00f1a Carrasco","Patricia Puerta","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/","name":"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg","datePublished":"2025-09-19T10:41:12+00:00","dateModified":"2025-09-19T10:41:58+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-registra-el-pacto-de-la-vivienda-de-castello-y-anima-al-pp-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV registra el Pacto de la Vivienda de Castell\u00f3 y anima al PP a sumarse a la propuesta y trabajar de forma consensuada para priorizar su ejecuci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250919-El-PSPV-registra-el-Pacto-de-la-Vivienda-de-Castello-y-anima-al-PP-a-sumarse-a-la-propuesta-y-trabajar-de-forma-consensuada-para-priorizar-su-ejecucion-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=8891"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8891\/revisions"}],"predecessor-version":[{"id":8896,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8891\/revisions\/8896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/8894"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=8891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=8891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=8891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}