{"id":8861,"date":"2025-09-15T14:04:32","date_gmt":"2025-09-15T12:04:32","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=8861"},"modified":"2026-03-24T08:56:01","modified_gmt":"2026-03-24T07:56:01","slug":"el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/","title":{"rendered":"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>Los representantes socialistas en la mesa de trabajo de las ordenanzas fiscales de 2026 lamentan la \u201ctibieza\u201d de las propuestas del Partido Popular, reclaman que el IBI compense con una bajada adecuada la subida de la tasa de basura y reclaman que se estudie reforzar las bonificaciones a los vecinos y vecinas que reciclan m\u00e1s<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.mp3\" autoplay><\/audio><\/figure>\n\n\n\n<p>El Grupo Municipal Socialista considera \u201cinsuficiente\u201d la propuesta de modificaci\u00f3n de las ordenanzas fiscales del Partido Popular para 2026 y lamenta la \u201ctibieza\u201d del gobierno municipal \u201cpara reducir en todo lo posible el efecto en los bolsillos de la ciudadan\u00eda del \u2018Basurazo de <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Carrasco<\/a>\u201d.<\/p>\n\n\n\n<p><a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/jose-luis-lopez\/\">Jos\u00e9 Luis L\u00f3pez<\/a>, portavoz adjunto del PSPV, se\u00f1ala que el 2 por ciento de rebaja del Impuesto de Bienes Inmuebles que propone el PP para el a\u00f1o que viene \u201ces una mera operaci\u00f3n de maquillaje\u201d. Al igual que ya propuso el grupo socialista para las ordenanzas fiscales de 2025, \u201chemos vuelto a exigir una compensaci\u00f3n adecuada de la subida de la tasa de basura con una mayo reducci\u00f3n del IBI\u201d.<\/p>\n\n\n\n<p>El Partido Socialista, en este sentido, insiste en que \u201ctoda la ciudadan\u00eda debe participar de forma justa en la financiaci\u00f3n del servicio de recogida y tratamiento de residuos, tal y como marca la normativa europea, pero el ayuntamiento tiene las herramientas para la econom\u00eda familiar no se resienta, algo que parece preocupar poco o nada a la se\u00f1ora Carrasco\u201d, se\u00f1ala L\u00f3pez.<\/p>\n\n\n\n<p>En la mesa de trabajo\u00a0L\u00f3pez, acompa\u00f1ado tambi\u00e9n por la edil socialista <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/mary-carmen-ribera\/\">Mary Carmen Ribera<\/a>,\u00a0ha reclamado al concejal de Hacienda, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/juan-carlos-redondo\/\">Juan Carlos Redondo<\/a>, que se trabaje tambi\u00e9n de forma en sistema de bonificaciones \u201cque premie m\u00e1s a los vecinos y vecinas que se impliquen en el reciclaje\u201d, m\u00e1s si cabe cuando el a\u00f1o que viene est\u00e1 previsto instalar en la ciudad contenedores inteligentes\u201d. Adem\u00e1s, se insiste en que el a\u00f1o que viene se articulen por fin f\u00f3rmulas para que los inquilinos de viviendas que pagan tasa de basuras puedan recibir tambi\u00e9n bonificaciones por reciclar\u201d.<\/p>\n\n\n\n<p>Otras propuestas socialistas, como ya qued\u00f3 recogido en el pleno ordinario del pasado mes de julio, son definir bonificaciones para los comercios que realizan un tratamiento adecuado de sus residuos, implantar una tasa proporcional al volumen de generado y acciones de concienciaci\u00f3n y colaboraci\u00f3n con la sociedad civil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal Socialista considera \u201cinsuficiente\u201d la propuesta de modificaci\u00f3n de las ordenanzas fiscales del Partido Popular para 2026 y lamenta la \u201ctibieza\u201d del gobierno municipal \u201cpara reducir en todo lo posible el efecto en los bolsillos de la ciudadan\u00eda del \u2018Basurazo de Carrasco\u201d. Jos\u00e9 Luis L\u00f3pez, portavoz adjunto del PSPV, se\u00f1ala que el 2 &#8230;<\/p>\n","protected":false},"author":48,"featured_media":8863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[1151,733,85,825,99,448],"class_list":["post-8861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-basurazo","tag-begona-carrasco","tag-jose-luis-lopez","tag-juan-carlos-redondo","tag-mary-carmen-ribera","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El Grupo Municipal Socialista considera \u201cinsuficiente\u201d la propuesta de modificaci\u00f3n de las ordenanzas fiscales del Partido Popular para 2026 y lamenta la \u201ctibieza\u201d del gobierno municipal \u201cpara reducir en todo lo posible el efecto en los bolsillos de la ciudadan\u00eda del \u2018Basurazo de Carrasco\u201d. Jos\u00e9 Luis L\u00f3pez, portavoz adjunto del PSPV, se\u00f1ala que el 2 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T12:04:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T07:56:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019\",\"datePublished\":\"2025-09-15T12:04:32+00:00\",\"dateModified\":\"2026-03-24T07:56:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg\",\"keywords\":[\"Basurazo\",\"Bego\u00f1a Carrasco\",\"Jos\u00e9 Luis L\u00f3pez\",\"Juan Carlos Redondo\",\"Mary Carmen Ribera\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/\",\"name\":\"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg\",\"datePublished\":\"2025-09-15T12:04:32+00:00\",\"dateModified\":\"2026-03-24T07:56:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg\",\"width\":1600,\"height\":1399},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3","og_description":"El Grupo Municipal Socialista considera \u201cinsuficiente\u201d la propuesta de modificaci\u00f3n de las ordenanzas fiscales del Partido Popular para 2026 y lamenta la \u201ctibieza\u201d del gobierno municipal \u201cpara reducir en todo lo posible el efecto en los bolsillos de la ciudadan\u00eda del \u2018Basurazo de Carrasco\u201d. Jos\u00e9 Luis L\u00f3pez, portavoz adjunto del PSPV, se\u00f1ala que el 2 ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-09-15T12:04:32+00:00","article_modified_time":"2026-03-24T07:56:01+00:00","og_image":[{"width":1600,"height":1399,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019","datePublished":"2025-09-15T12:04:32+00:00","dateModified":"2026-03-24T07:56:01+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg","keywords":["Basurazo","Bego\u00f1a Carrasco","Jos\u00e9 Luis L\u00f3pez","Juan Carlos Redondo","Mary Carmen Ribera","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/","name":"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg","datePublished":"2025-09-15T12:04:32+00:00","dateModified":"2026-03-24T07:56:01+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg","width":1600,"height":1399},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-pide-al-ayuntamiento-de-castello-medidas-mas-ambiciosas-para-paliar-el-basurazo-de-carrasco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV pide al Ayuntamiento de Castell\u00f3 medidas m\u00e1s ambiciosas para paliar el \u2018Basurazo de Carrasco\u2019"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/09\/20250915-El-PSPV-pide-al-Ayuntamiento-de-Castello-medidas-mas-ambiciosas-para-paliar-el-\u2018Basurazo-de-Carrasco.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=8861"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8861\/revisions"}],"predecessor-version":[{"id":8865,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8861\/revisions\/8865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/8863"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=8861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=8861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=8861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}