{"id":8703,"date":"2025-08-21T10:20:44","date_gmt":"2025-08-21T08:20:44","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=8703"},"modified":"2025-08-25T10:26:00","modified_gmt":"2025-08-25T08:26:00","slug":"el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/","title":{"rendered":"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em><strong>La portavoz socialista, Patricia Puerta, recuerda que los \u00fanicos centros\u00a0abiertos para pacientes de ambas enfermedades fueron puestos en marcha por los anteriores gobiernos de progreso del Ayuntamiento de Castell\u00f3 y la Generalitat liderados por el PSPV-PSOE<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson.mp3\" autoplay><\/audio><\/figure>\n\n\n\n<p>El pacto de gobierno PPVox suscrito\u00a0hace dos a\u00f1os\u00a0recogi\u00f3\u00a0como una de sus principales iniciativas la puesta en marcha de unidades de respiro para pacientes con alzh\u00e9imer y p\u00e1rkinson por todos los distritos de Castell\u00f3, \u201cpero la realidad es que estamos ante otro enga\u00f1o m\u00e1s de la alcaldesa, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a>, que va a ser incapaz de abrirlos durante la presente legislatura\u201d.<\/p>\n\n\n\n<p><a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>, portavoz del Grupo Municipal Socialista en el ayuntamiento, se\u00f1ala que \u201cel paso del tiempo deja a cada uno en su sitio, y dos a\u00f1os despu\u00e9s de que Carrasco firmase el Pacto de la Verg\u00fcenza para meter a la ultraderecha en el gobierno municipal, vemos como sus promesas, en especial las vinculadas a las pol\u00edticas sociales, han desaparecido\u201d.<\/p>\n\n\n\n<p>La alcaldesa, como recuerda la portavoz socialista, \u201chizo bandera durante la campa\u00f1a electoral de la apertura de estas unidades de respiro en cada uno de los seis distritos de la ciudad, pero vemos que ya hemos cruzado el ecuador del mandato sin que haya ni siquiera mencionado s\u00ed ha trabajado algo en gestionar esta promesa, o es que el rato que le dedica a hacerse fotos para las redes sociales no le deja tiempo para trabajar en las necesidades reales de las y los castellonenses\u201d.<\/p>\n\n\n\n<p>Patricia Puerta destaca&nbsp;adem\u00e1s que, tanto el Centro de P\u00e1rkinson de Castell\u00f3, que abri\u00f3 sus puertas a principios de este a\u00f1o 2025,&nbsp;como&nbsp;el&nbsp;Centro de D\u00eda La Pineda para enfermos de alzh\u00e9imer, en las instalaciones de Tetu\u00e1n XIV, \u201cson iniciativas que activaron los gobiernos de progreso liderados por el Partido Socialista en el ayuntamiento y en la Generalitat\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pacto de gobierno PPVox suscrito\u00a0hace dos a\u00f1os\u00a0recogi\u00f3\u00a0como una de sus principales iniciativas la puesta en marcha de unidades de respiro para pacientes con alzh\u00e9imer y p\u00e1rkinson por todos los distritos de Castell\u00f3, \u201cpero la realidad es que estamos ante otro enga\u00f1o m\u00e1s de la alcaldesa, Bego\u00f1a Carrasco, que va a ser incapaz de abrirlos &#8230;<\/p>\n","protected":false},"author":48,"featured_media":8705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[733,81,448],"class_list":["post-8703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-begona-carrasco","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El pacto de gobierno PPVox suscrito\u00a0hace dos a\u00f1os\u00a0recogi\u00f3\u00a0como una de sus principales iniciativas la puesta en marcha de unidades de respiro para pacientes con alzh\u00e9imer y p\u00e1rkinson por todos los distritos de Castell\u00f3, \u201cpero la realidad es que estamos ante otro enga\u00f1o m\u00e1s de la alcaldesa, Bego\u00f1a Carrasco, que va a ser incapaz de abrirlos ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-21T08:20:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T08:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson\",\"datePublished\":\"2025-08-21T08:20:44+00:00\",\"dateModified\":\"2025-08-25T08:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg\",\"keywords\":[\"Bego\u00f1a Carrasco\",\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/\",\"name\":\"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg\",\"datePublished\":\"2025-08-21T08:20:44+00:00\",\"dateModified\":\"2025-08-25T08:26:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson - PSPV-PSOE CASTELL\u00d3","og_description":"El pacto de gobierno PPVox suscrito\u00a0hace dos a\u00f1os\u00a0recogi\u00f3\u00a0como una de sus principales iniciativas la puesta en marcha de unidades de respiro para pacientes con alzh\u00e9imer y p\u00e1rkinson por todos los distritos de Castell\u00f3, \u201cpero la realidad es que estamos ante otro enga\u00f1o m\u00e1s de la alcaldesa, Bego\u00f1a Carrasco, que va a ser incapaz de abrirlos ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-08-21T08:20:44+00:00","article_modified_time":"2025-08-25T08:26:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson","datePublished":"2025-08-21T08:20:44+00:00","dateModified":"2025-08-25T08:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg","keywords":["Bego\u00f1a Carrasco","Patricia Puerta","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/","name":"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg","datePublished":"2025-08-21T08:20:44+00:00","dateModified":"2025-08-25T08:26:00+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-afea-a-begona-carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV afea a\u00a0Bego\u00f1a Carrasco\u00a0su promesa sin cumplir\u00a0de crear unidades de respiro por distritos para pacientes con alzh\u00e9imer y p\u00e1rkinson"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/08\/20250821-El-PSPV-afea-a-Begona-Carrasco-su-promesa-sin-cumplir-de-crear-unidades-de-respiro-por-distritos-para-pacientes-con-alzheimer-y-parkinson-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=8703"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8703\/revisions"}],"predecessor-version":[{"id":8711,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8703\/revisions\/8711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/8705"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=8703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=8703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=8703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}