{"id":8570,"date":"2025-07-29T10:57:33","date_gmt":"2025-07-29T08:57:33","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=8570"},"modified":"2025-07-29T10:58:28","modified_gmt":"2025-07-29T08:58:28","slug":"pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/","title":{"rendered":"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em><strong>El equipo de gobierno desestima la enmienda del PSPV a las cuentas del Pacto Local por el Empleo que pretend\u00eda dotar con 150.000 euros la l\u00ednea de esta subvenci\u00f3n<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello.mp3\" autoplay><\/audio><\/figure>\n\n\n\n<p>El equipo de gobierno de Castell\u00f3 ha desestimado la enmienda en favor de la contrataci\u00f3n de personas desempleadas en entidades de econom\u00eda social presentada por el Grupo Municipal Socialista a las cuentas de 2026 del Consorcio del Pacto Local por el Empleo. Se trata de la l\u00ednea de ayudas a la Econom\u00eda Social que nacieron en 2017 y que PP-Vox ya anul\u00f3 en 2025.<\/p>\n\n\n\n<p>La portavoz del Grupo Municipal Socialista, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>, ha recordado que fue un gobierno progresista el que impuls\u00f3 hace ocho a\u00f1os en Castell\u00f3 esta l\u00ednea de ayudas para fomentar la\u00a0contrataci\u00f3n de personas desempleadas en entidades de econom\u00eda social como cooperativas, empresas de inserci\u00f3n laboral, mutualidades, fundaciones, asociaciones y centros especiales de empleo, entre otros.<\/p>\n\n\n\n<p>La acogida de aquella medida por parte de la ciudadan\u00eda provoc\u00f3 que, hasta 2023, todas las ayudas presupuestadas se concedieran \u00edntegramente hasta agotar los fondos municipales. De hecho, en algunas de las convocatorias, el PSPV y sus socios de gobierno ampliaron el cr\u00e9dito disponible para poder llegar a m\u00e1s personas desempleadas de Castell\u00f3 a trav\u00e9s de este eje.<\/p>\n\n\n\n<p>El balance del impacto entre 2017 y 2023 fue evidente: el Ayuntamiento concedi\u00f3 886.000 euros que permitieron asumir 68 nuevas altas en la Seguridad Social y la creaci\u00f3n de 10 nuevas empresas en la ciudad. Estas cifras han motivado que, despu\u00e9s de que PP-Vox anularan en 2025 la mayor parte de los ep\u00edgrafes destinados a&nbsp;favorecer el desarrollo socioecon\u00f3mico de la ciudad y fomentar el empleo estable y de calidad, el Grupo Municipal Socialista considere necesaria la puesta en marcha de nuevo de esta l\u00ednea de ayudas.<\/p>\n\n\n\n<p>As\u00ed lo ha manifestado la portavoz socialista durante el debate de las cuentas del Consorcio del Pacto Local por el Empleo:&nbsp;\u201cCon esta estrategia pol\u00edtica, la derecha desmantela el sistema de ayudas para la contrataci\u00f3n de personas desempleadas de nuestra ciudad dejando claro cu\u00e1l es su apuesta por la inserci\u00f3n laboral de los m\u00e1s vulnerables\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de gobierno de Castell\u00f3 ha desestimado la enmienda en favor de la contrataci\u00f3n de personas desempleadas en entidades de econom\u00eda social presentada por el Grupo Municipal Socialista a las cuentas de 2026 del Consorcio del Pacto Local por el Empleo. Se trata de la l\u00ednea de ayudas a la Econom\u00eda Social que nacieron &#8230;<\/p>\n","protected":false},"author":48,"featured_media":8572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[81,448],"class_list":["post-8570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3 - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3 - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El equipo de gobierno de Castell\u00f3 ha desestimado la enmienda en favor de la contrataci\u00f3n de personas desempleadas en entidades de econom\u00eda social presentada por el Grupo Municipal Socialista a las cuentas de 2026 del Consorcio del Pacto Local por el Empleo. Se trata de la l\u00ednea de ayudas a la Econom\u00eda Social que nacieron ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T08:57:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T08:58:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1734\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3\",\"datePublished\":\"2025-07-29T08:57:33+00:00\",\"dateModified\":\"2025-07-29T08:58:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg\",\"keywords\":[\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/\",\"name\":\"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3 - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg\",\"datePublished\":\"2025-07-29T08:57:33+00:00\",\"dateModified\":\"2025-07-29T08:58:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg\",\"width\":2560,\"height\":1734},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3 - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/","og_locale":"es_ES","og_type":"article","og_title":"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3 - PSPV-PSOE CASTELL\u00d3","og_description":"El equipo de gobierno de Castell\u00f3 ha desestimado la enmienda en favor de la contrataci\u00f3n de personas desempleadas en entidades de econom\u00eda social presentada por el Grupo Municipal Socialista a las cuentas de 2026 del Consorcio del Pacto Local por el Empleo. Se trata de la l\u00ednea de ayudas a la Econom\u00eda Social que nacieron ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-07-29T08:57:33+00:00","article_modified_time":"2025-07-29T08:58:28+00:00","og_image":[{"width":2560,"height":1734,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3","datePublished":"2025-07-29T08:57:33+00:00","dateModified":"2025-07-29T08:58:28+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg","keywords":["Patricia Puerta","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/","url":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/","name":"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3 - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg","datePublished":"2025-07-29T08:57:33+00:00","dateModified":"2025-07-29T08:58:28+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg","width":2560,"height":1734},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/pp-y-vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-castello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"PP y Vox vuelven a dejar a cero las ayudas para proyectos de econom\u00eda social en Castell\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/07\/20250729-PP-y-Vox-vuelven-a-dejar-a-cero-las-ayudas-para-proyectos-de-economia-social-en-Castello-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=8570"}],"version-history":[{"count":6,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8570\/revisions"}],"predecessor-version":[{"id":8578,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8570\/revisions\/8578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/8572"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=8570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=8570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=8570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}