{"id":8266,"date":"2025-06-21T21:24:55","date_gmt":"2025-06-21T19:24:55","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=8266"},"modified":"2025-06-21T21:24:56","modified_gmt":"2025-06-21T19:24:56","slug":"el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/","title":{"rendered":"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em><strong>El Grupo Municipal Socialista registra una declaraci\u00f3n institucional, para su aprobaci\u00f3n en el pleno, que contempla reclamar m\u00e1s dotaci\u00f3n presupuestaria al Gobierno de Espa\u00f1a para trabajar en protocolos espec\u00edficos y formar a personal municipal en materia de diversidad sexual y de g\u00e9nero<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/06\/20250621-El-PSPV-reclama-un-apoyo-firme-al-colectivo-LGTBI-y-la-condena-del-Ayuntamiento-de-Castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local.mp3\" autoplay><\/audio><\/figure>\n\n\n\n<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado una declaraci\u00f3n institucional para conmemorar el D\u00eda Internacional del Orgullo LGTBI, que se celebra el 28 de junio, una fecha de alcance mundial que celebra la diversidad y recuerda la importancia de garantizar los derechos y libertades de todas las personas, con independencia de su orientaci\u00f3n sexual.<\/p>\n\n\n\n<p>La propuesta, presentada para su aprobaci\u00f3n el pr\u00f3ximo pleno, recoge tres puntos de acuerdo para los que es necesario el apoyo de todos los los grupos pol\u00edticos. Por un lado, se insta al Gobierno de Espa\u00f1a a dotar de la dotaci\u00f3n presupuestaria espec\u00edfica y sostenida a los gobiernos locales para que puedan seguir trabajando en cuestiones como protocolos espec\u00edficos para la atenci\u00f3n integral a v\u00edctimas de agresiones motivadas por intolerancia, priorizando la protecci\u00f3n de menores, personas trans y colectivos especialmente vulnerables.<\/p>\n\n\n\n<p>Un presupuesto que tambi\u00e9n debe garantizarse para la formaci\u00f3n del personal municipal, especialmente en \u00e1reas como servicios sociales, seguridad ciudadana y educaci\u00f3n, as\u00ed como en materia de diversidad sexual y de g\u00e9nero. Y a ello se une el desarrollo de campa\u00f1as educativas y de sensibilizaci\u00f3n que promuevan la convivencia, la tolerancia y el respeto a todas las personas.<\/p>\n\n\n\n<p>Por otro lado, se insta al \u00f3rgano municipal competente a desarrollar iniciativas que refuercen la inclusi\u00f3n y el reconocimiento de todas las personas, con especial atenci\u00f3n a quienes se encuentran en mayor situaci\u00f3n de vulnerabilidad. \u201cLa dignidad y la igualdad no deben ser esl\u00f3ganes, sino principios reales, sostenidos desde el trabajo conjunto, la responsabilidad democr\u00e1tica y el respeto a la libertad de todas las personas\u201d, se\u00f1ala el portavoz adjunto del grupo socialista, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/jose-luis-lopez\/\">Jos\u00e9 Luis L\u00f3pez<\/a>.<\/p>\n\n\n\n<p>Adem\u00e1s, en la declaraci\u00f3n institucional se recoge como punto a aprobar por todos los grupos que la corporaci\u00f3n municipal \u201cmuestre su rechazo y condena de las declaraciones hom\u00f3fobas realizadas por parte de miembros del equipo de gobierno municipal\u201d.<\/p>\n\n\n\n<p>El D\u00eda Internacional del Orgullo LGTBI tiene su origen en los hechos ocurridos en 1969 en el barrio neoyorquino de Stonewall, que marcaron un antes y un despu\u00e9s en la reivindicaci\u00f3n de los derechos civiles del colectivo LGTBI. Desde entonces, esta fecha se ha consolidado como una oportunidad para reflexionar, reconocer los avances logrados y seguir construyendo una sociedad donde la dignidad, la libertad y la igualdad plena sea una realidad para todos.<\/p>\n\n\n\n<p>En este 2025, \u201cel Ayuntamiento de Castell\u00f3 de la Plana ha de reiterar su firme compromiso con los valores democr\u00e1ticos de igualdad, respeto, libertad y dignidad\u201d, se\u00f1ala L\u00f3pez, quien subraya que no podemos permitir que se difundan mensajes hom\u00f3fobos y ataques al colectivo LGTBI desde los ayuntamientos, como recientemente ha ocurrido en Castell\u00f3 por parte de responsables pol\u00edticos con responsabilidad de gobierno\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado una declaraci\u00f3n institucional para conmemorar el D\u00eda Internacional del Orgullo LGTBI, que se celebra el 28 de junio, una fecha de alcance mundial que celebra la diversidad y recuerda la importancia de garantizar los derechos y libertades de todas las personas, con independencia de su &#8230;<\/p>\n","protected":false},"author":48,"featured_media":7998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[85,448],"class_list":["post-8266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-jose-luis-lopez","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado una declaraci\u00f3n institucional para conmemorar el D\u00eda Internacional del Orgullo LGTBI, que se celebra el 28 de junio, una fecha de alcance mundial que celebra la diversidad y recuerda la importancia de garantizar los derechos y libertades de todas las personas, con independencia de su ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-21T19:24:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-21T19:24:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local\",\"datePublished\":\"2025-06-21T19:24:55+00:00\",\"dateModified\":\"2025-06-21T19:24:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/\"},\"wordCount\":554,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg\",\"keywords\":[\"Jos\u00e9 Luis L\u00f3pez\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/\",\"name\":\"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg\",\"datePublished\":\"2025-06-21T19:24:55+00:00\",\"dateModified\":\"2025-06-21T19:24:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local - PSPV-PSOE CASTELL\u00d3","og_description":"El Grupo Municipal Socialista del Ayuntamiento de Castell\u00f3 ha registrado una declaraci\u00f3n institucional para conmemorar el D\u00eda Internacional del Orgullo LGTBI, que se celebra el 28 de junio, una fecha de alcance mundial que celebra la diversidad y recuerda la importancia de garantizar los derechos y libertades de todas las personas, con independencia de su ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-06-21T19:24:55+00:00","article_modified_time":"2025-06-21T19:24:56+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local","datePublished":"2025-06-21T19:24:55+00:00","dateModified":"2025-06-21T19:24:56+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/"},"wordCount":554,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg","keywords":["Jos\u00e9 Luis L\u00f3pez","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/","name":"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg","datePublished":"2025-06-21T19:24:55+00:00","dateModified":"2025-06-21T19:24:56+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-reclama-un-apoyo-firme-al-colectivo-lgtbi-y-la-condena-del-ayuntamiento-de-castello-a-las-declaraciones-homofobas-de-ediles-del-gobierno-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV reclama un apoyo firme al colectivo LGTBI y la condena del Ayuntamiento de Castell\u00f3 a las declaraciones hom\u00f3fobas de ediles del gobierno local"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/05\/20250521-El-PSPV-reclama-en-una-mocion-a-Carrasco-que-active-un-Plan-Municipal-de-Ayudas-al-Alquiler-para-ayudar-a-familias-vulnerables-y-a-la-juventud-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=8266"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8266\/revisions"}],"predecessor-version":[{"id":8269,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/8266\/revisions\/8269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/7998"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=8266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=8266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=8266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}