{"id":6253,"date":"2024-10-02T15:50:26","date_gmt":"2024-10-02T13:50:26","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=6253"},"modified":"2024-10-02T15:50:27","modified_gmt":"2024-10-02T13:50:27","slug":"el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/","title":{"rendered":"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos"},"content":{"rendered":"\n<p><em>\u25cf<\/em> <em><strong>La concejala socialista Mary Carmen Ribera denuncia \u201cla descomunal presencia de mosquitos en la ciudad, en especial en el Grau, que ha pillado al equipo de gobierno de PP y Vox sin capacidad de reacci\u00f3n\u201d<\/strong><\/em><\/p>\n\n\n\n<p>El Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3 ha denunciado \u201cla falta de previsi\u00f3n\u201d del equipo de gobierno que preside <strong>Bego\u00f1a Carrasco<\/strong> tras el episodio de lluvias registrado en el municipio y las elevadas temperaturas posteriores, que ha llevado a que \u201cestemos viviendo estos d\u00edas una aut\u00e9ntica plaga de mosquitos en Castell\u00f3 y el Grau sin que PP y Vox se den por enterados\u201d.<\/p>\n\n\n\n<p><strong>Mary Carmen Ribera<\/strong>, concejala socialista responsable de las \u00e1reas de Salud P\u00fablica y el Grau, se\u00f1ala que la alcaldesa que, \u201cya que le gusta tanto el postureo en las redes sociales, se detenga a leer los comentarios de la ciudadan\u00eda, que deja bien claro que no se puede salir a la calle ni ir a la playa a riesgo de ser acribillados por las picaduras de mosquitos\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"671\" height=\"1024\" data-attachment-id=\"6255\" data-permalink=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/20241002-el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos-1\/\" data-orig-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1.jpg\" data-orig-size=\"828,1263\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1-197x300.jpg\" data-large-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1-671x1024.jpg\" data-id=\"6255\" src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1-671x1024.jpg\" alt=\"\" class=\"wp-image-6255\" srcset=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1-671x1024.jpg 671w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1-197x300.jpg 197w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1-768x1171.jpg 768w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-1.jpg 828w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"1024\" data-attachment-id=\"6256\" data-permalink=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/20241002-el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos-2\/\" data-orig-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2.jpg\" data-orig-size=\"713,1239\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2-173x300.jpg\" data-large-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2-589x1024.jpg\" data-id=\"6256\" src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2-589x1024.jpg\" alt=\"\" class=\"wp-image-6256\" srcset=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2-589x1024.jpg 589w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2-173x300.jpg 173w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-2.jpg 713w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"653\" height=\"1024\" data-attachment-id=\"6257\" data-permalink=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/20241002-el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos-3\/\" data-orig-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3.jpg\" data-orig-size=\"799,1253\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3-191x300.jpg\" data-large-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3-653x1024.jpg\" data-id=\"6257\" src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3-653x1024.jpg\" alt=\"\" class=\"wp-image-6257\" srcset=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3-653x1024.jpg 653w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3-191x300.jpg 191w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3-768x1204.jpg 768w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-3.jpg 799w\" sizes=\"auto, (max-width: 653px) 100vw, 653px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"1024\" data-attachment-id=\"6258\" data-permalink=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/20241002-el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos-4\/\" data-orig-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4.jpg\" data-orig-size=\"828,1237\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4-201x300.jpg\" data-large-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4-685x1024.jpg\" data-id=\"6258\" src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4-685x1024.jpg\" alt=\"\" class=\"wp-image-6258\" srcset=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4-685x1024.jpg 685w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4-201x300.jpg 201w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4-768x1147.jpg 768w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-4.jpg 828w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"1024\" data-attachment-id=\"6259\" data-permalink=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/20241002-el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos-5\/\" data-orig-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5.jpg\" data-orig-size=\"747,1243\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5-180x300.jpg\" data-large-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5-615x1024.jpg\" data-id=\"6259\" src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5-615x1024.jpg\" alt=\"\" class=\"wp-image-6259\" srcset=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5-615x1024.jpg 615w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5-180x300.jpg 180w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos-5.jpg 747w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Quejas vecinales por los mosquitos<\/figcaption><\/figure>\n\n\n\n<p>En el pleno ordinario del pasado 26 de septiembre Ribera, en el apartado de ruegos y preguntas, ya advirti\u00f3 a Bego\u00f1a Carrasco de su \u201cdejadez\u201d a la hora de actuar en la prevenci\u00f3n de la aparici\u00f3n de mosquitos, \u201calgo que queda constatado estos d\u00edas en los que se hace imposible pasear en el Grau y la Marjaleria o diversos puntos de la ciudad, como la zona de Sensal o el Pau Lled\u00f3, entre otras\u201d.<\/p>\n\n\n\n<p>Ribera le record\u00f3 en el pleno a Bego\u00f1a Carrasco \u201csu demagogia cuando estaba en la oposici\u00f3n, desde donde utiliz\u00f3 el tema de los mosquitos como arma arrojadiza, cuando sab\u00eda que se estaban aplicando los procedimientos adecuados para combatirlos\u201d. Ahora, \u201cla realidad a la que se asoma la alcaldesa es que se han visto desbordados por las plagas, por mucho que est\u00e9 anunciando que se van a incrementar los recursos econ\u00f3micos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25cf La concejala socialista Mary Carmen Ribera denuncia \u201cla descomunal presencia de mosquitos en la ciudad, en especial en el Grau, que ha pillado al equipo de gobierno de PP y Vox sin capacidad de reacci\u00f3n\u201d El Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3 ha denunciado \u201cla falta de previsi\u00f3n\u201d del equipo de gobierno &#8230;<\/p>\n","protected":false},"author":48,"featured_media":6254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[99,448],"class_list":["post-6253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-mary-carmen-ribera","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"\u25cf La concejala socialista Mary Carmen Ribera denuncia \u201cla descomunal presencia de mosquitos en la ciudad, en especial en el Grau, que ha pillado al equipo de gobierno de PP y Vox sin capacidad de reacci\u00f3n\u201d El Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3 ha denunciado \u201cla falta de previsi\u00f3n\u201d del equipo de gobierno ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-02T13:50:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T13:50:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos\",\"datePublished\":\"2024-10-02T13:50:26+00:00\",\"dateModified\":\"2024-10-02T13:50:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/\"},\"wordCount\":357,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg\",\"keywords\":[\"Mary Carmen Ribera\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/\",\"name\":\"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg\",\"datePublished\":\"2024-10-02T13:50:26+00:00\",\"dateModified\":\"2024-10-02T13:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg\",\"width\":1010,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos - PSPV-PSOE CASTELL\u00d3","og_description":"\u25cf La concejala socialista Mary Carmen Ribera denuncia \u201cla descomunal presencia de mosquitos en la ciudad, en especial en el Grau, que ha pillado al equipo de gobierno de PP y Vox sin capacidad de reacci\u00f3n\u201d El Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3 ha denunciado \u201cla falta de previsi\u00f3n\u201d del equipo de gobierno ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2024-10-02T13:50:26+00:00","article_modified_time":"2024-10-02T13:50:27+00:00","og_image":[{"width":1010,"height":555,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos","datePublished":"2024-10-02T13:50:26+00:00","dateModified":"2024-10-02T13:50:27+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/"},"wordCount":357,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg","keywords":["Mary Carmen Ribera","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/","name":"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg","datePublished":"2024-10-02T13:50:26+00:00","dateModified":"2024-10-02T13:50:27+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg","width":1010,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-acusa-a-begona-carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-castello-y-el-grau-acribillados-por-plagas-de-mosquitos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV acusa a Bego\u00f1a Carrasco \u201cabandonar a su suerte\u201d a los vecinos y vecinas de Castell\u00f3 y el Grau, \u201cacribillados\u201d por plagas de mosquitos"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/10\/20241002-El-PSPV-acusa-a-Begona-Carrasco-abandonar-a-su-suerte-a-los-vecinos-y-vecinas-de-Castello-y-el-Grau-acribillados-por-plagas-de-mosquitos.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/6253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=6253"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/6253\/revisions"}],"predecessor-version":[{"id":6261,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/6253\/revisions\/6261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/6254"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=6253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=6253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=6253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}