{"id":6087,"date":"2024-09-16T12:09:29","date_gmt":"2024-09-16T10:09:29","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=6087"},"modified":"2024-09-16T12:13:32","modified_gmt":"2024-09-16T10:13:32","slug":"la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/","title":{"rendered":"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l&#8217;autor o autors"},"content":{"rendered":"\n<p><em>\u25cf<\/em> <em><strong>Jos\u00e9 Luis L\u00f3pez, vicesecretari\u00a0i adjunt a la secretaria d&#8217;Organitzaci\u00f3 del PSPV de Castell\u00f3, lamenta \u201cl&#8217;actitud de l&#8217;actual equip de govern de l&#8217;Ajuntament, que mai va voler personar-se en la causa malgrat quedar constatats els danys en el patrimoni de la ciutat\u201d<\/strong><\/em><\/p>\n\n\n\n<p>\u25cf <em><strong>L\u00f3pez considera \u201cinacceptable\u201d que per al govern PPVox \u201cnetejar les pintades de \u2018Ortol\u00e1 caraculo\u2019 s\u00ed que tinguen un cost econ\u00f2mic de m\u00e9s de 70.000 euros i les que afectaven el PSOE, moltes d&#8217;elles encara presents als carrers de la ciutat, no suposaren cap despesa en estar incloses, segons diuen, en el contracte de neteja del consistori\u201d<\/strong><\/em><\/p>\n\n\n\n<p>\u25cf <em><strong>En la investigaci\u00f3 judicial es va analitzar la pres\u00e8ncia d&#8217;una furgoneta negra per la seua possible vinculaci\u00f3 als fets, vehicle que, despr\u00e9s de les perquisicions de la Policia Nacional, es va determinar que va ser llogat per l&#8217;actual regidor de Mobilitat del PP, Cristian Ram\u00edrez<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/09\/20240916-El-auto-del-juez-constata-la-campana-de-vejaciones-contra-el-PSOE-en-el-caso-Corrupsoe.mp3\" autoplay><\/audio><figcaption class=\"wp-element-caption\">Declaracions Jos\u00e9 Luis L\u00f3pez<\/figcaption><\/figure>\n\n\n\n<p>L&#8217;aute del Jutjat d&#8217;Instrucci\u00f3 4 de Castell\u00f3, que ha decidit el sobrese\u00efment de la causa per la campanya de pintades contra el Partit Socialista durant l&#8217;any 2023, \u201cconfirma que les expressions \u2018Corrupsoe\u2019 i \u2018GOLPSOE d&#8217;Estat\u2019 tenien un contingut vexatori\u201d, si b\u00e9 considera que \u201cno \u00e9s discriminatori ni cont\u00e9 c\u00e0rrega que incite directament o indirectament a la realitzaci\u00f3 d&#8217;actes violents cap a cap col\u00b7lectiu\u201d.<\/p>\n\n\n\n<p><strong>Jos\u00e9 Luis L\u00f3pez<\/strong>, vicesecretari i adjunt a l&#8217;\u00e0rea d&#8217;Organitzaci\u00f3 del Partit Socialista de Castell\u00f3, considera que \u201cqueda constatada la t\u00f2xica campanya que va patir durant mesos el PSOE, amb vexacions per tota la ciutat, per\u00f2 al final el jutjat ha decidit que no \u00e9s un discurs d&#8217;odi i que no s&#8217;ha pogut identificar a l&#8217;autor o autors dels fets\u201d.<\/p>\n\n\n\n<p>L\u00f3pez, sobretot aquest procediment, assenyala que \u201cens ha servit tamb\u00e9 per a constatar una realitat: que el Partit Popular es creu que l&#8217;ajuntament \u00e9s seu, perqu\u00e8 ens sembla lamentable que decidiren no personar-se en la causa, malgrat els danys en el patrimoni de tots els i les castellonenques\u201d.<\/p>\n\n\n\n<p>Aquesta realitat contrasta amb fets similars, com les pintades de \u2018Ortol\u00e1 caraculo\u2019 que han aparegut per la ciutat durant els \u00faltims mesos. \u201cQue des del govern municipal PPVox diguen, d&#8217;una banda, que netejar les frases contra el PSOE estava dins del contracte municipal de neteja, per la qual cosa no tenien sobrecost, per\u00f2 d&#8217;altra banda hagen valorat en m\u00e9s de 70.000 euros l&#8217;esborrament de les dirigides a <strong>Ortol\u00e1<\/strong> ens mostra la doble vara de mesurar del govern de <strong>Bego\u00f1a Carrasco<\/strong>\u201d, lamenta Jos\u00e9 Luis L\u00f3pez.<\/p>\n\n\n\n<p>El mobiliari urb\u00e0 de Castell\u00f3, tal com assenyala el dirigent socialista, \u201ces va veure seriosament afectat per aquestes pintades, per\u00f2 sembla que a l&#8217;ajuntament de Carrasco no li importa que haja tingut un cost econ\u00f2mic que ha afectat a tota la ciutadania\u201d.<\/p>\n\n\n\n<p>Sobre la investigaci\u00f3 del jutjat, Jos\u00e9 Luis L\u00f3pez recorda que en el procediment es va analitzar la pres\u00e8ncia d&#8217;una furgoneta negra al costat de diverses de les pintades. La investigaci\u00f3 de la Policia Nacional va determinar que li vehicle estava llogat per l&#8217;actual regidor de Mobilitat, <strong>Cristian Ram\u00edrez<\/strong>, que en l&#8217;\u00e8poca de les pintades formava part de la candidatura del Partit Popular. No obstant aix\u00f2, el jutjat no ha pogut confirmar l&#8217;autoria de les pintades.<\/p>\n\n\n\n<p>Malgrat aquest sobrese\u00efment dels fets, Jos\u00e9 Luis L\u00f3pez insisteix que \u201ctota la ciutadania va poder constatar, en els mesos previs a les eleccions municipals de 2023, \u201cla infame campanya que es va realitzar contra el Partit Socialista a Castell\u00f3, amb l&#8217;aparici\u00f3 de frases vexat\u00f2ries per tota la prov\u00edncia que, sens dubte, van alterar la neteja i respecte que se li suposa a qualsevol campanya electoral\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25cf Jos\u00e9 Luis L\u00f3pez, vicesecretari\u00a0i adjunt a la secretaria d&#8217;Organitzaci\u00f3 del PSPV de Castell\u00f3, lamenta \u201cl&#8217;actitud de l&#8217;actual equip de govern de l&#8217;Ajuntament, que mai va voler personar-se en la causa malgrat quedar constatats els danys en el patrimoni de la ciutat\u201d \u25cf L\u00f3pez considera \u201cinacceptable\u201d que per al govern PPVox \u201cnetejar les pintades de &#8230;<\/p>\n","protected":false},"author":48,"featured_media":3680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[87,446],"class_list":["post-6087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms-va","tag-jose-luis-lopez-va","tag-todos-va"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l&#039;autor o autors - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l&#039;autor o autors - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"\u25cf Jos\u00e9 Luis L\u00f3pez, vicesecretari\u00a0i adjunt a la secretaria d&#8217;Organitzaci\u00f3 del PSPV de Castell\u00f3, lamenta \u201cl&#8217;actitud de l&#8217;actual equip de govern de l&#8217;Ajuntament, que mai va voler personar-se en la causa malgrat quedar constatats els danys en el patrimoni de la ciutat\u201d \u25cf L\u00f3pez considera \u201cinacceptable\u201d que per al govern PPVox \u201cnetejar les pintades de ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-16T10:09:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T10:13:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l&#8217;autor o autors\",\"datePublished\":\"2024-09-16T10:09:29+00:00\",\"dateModified\":\"2024-09-16T10:13:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/\"},\"wordCount\":636,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg\",\"keywords\":[\"Jos\u00e9 Luis L\u00f3pez\",\"Todos\"],\"articleSection\":[\"Grup Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/\",\"name\":\"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l'autor o autors - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg\",\"datePublished\":\"2024-09-16T10:09:29+00:00\",\"dateModified\":\"2024-09-16T10:13:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l&#8217;autor o autors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l'autor o autors - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/","og_locale":"es_ES","og_type":"article","og_title":"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l'autor o autors - PSPV-PSOE CASTELL\u00d3","og_description":"\u25cf Jos\u00e9 Luis L\u00f3pez, vicesecretari\u00a0i adjunt a la secretaria d&#8217;Organitzaci\u00f3 del PSPV de Castell\u00f3, lamenta \u201cl&#8217;actitud de l&#8217;actual equip de govern de l&#8217;Ajuntament, que mai va voler personar-se en la causa malgrat quedar constatats els danys en el patrimoni de la ciutat\u201d \u25cf L\u00f3pez considera \u201cinacceptable\u201d que per al govern PPVox \u201cnetejar les pintades de ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2024-09-16T10:09:29+00:00","article_modified_time":"2024-09-16T10:13:32+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l&#8217;autor o autors","datePublished":"2024-09-16T10:09:29+00:00","dateModified":"2024-09-16T10:13:32+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/"},"wordCount":636,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg","keywords":["Jos\u00e9 Luis L\u00f3pez","Todos"],"articleSection":["Grup Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/","url":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/","name":"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l'autor o autors - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg","datePublished":"2024-09-16T10:09:29+00:00","dateModified":"2024-09-16T10:13:32+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/la-interlocutoria-del-jutge-constata-la-campanya-de-vexacions-contra-el-psoe-en-el-cas-corrupsoe-encara-que-decideix-arxivar-el-cas-al-no-poder-identificar-a-lautor-o-autors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"La interlocut\u00f2ria\u00a0del jutge constata la campanya de vexacions contra el PSOE en el cas Corrupsoe encara que decideix arxivar el cas al no poder identificar a l&#8217;autor o autors"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240116-Jose-Luis-Lopez-espera-que-el-Ayuntamiento-de-Castello-se-persone-como-afectado-en-la-denuncia-de-las-pintadas-y-pegatinas-contra-el-PSOE-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/6087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=6087"}],"version-history":[{"count":5,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/6087\/revisions"}],"predecessor-version":[{"id":6097,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/6087\/revisions\/6097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/3680"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=6087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=6087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=6087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}