{"id":5762,"date":"2024-07-26T13:04:21","date_gmt":"2024-07-26T11:04:21","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=5762"},"modified":"2024-07-26T13:19:27","modified_gmt":"2024-07-26T11:19:27","slug":"el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/","title":{"rendered":"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local"},"content":{"rendered":"\n<p>\u25cf <strong><em>L\u00f3pez lamenta que el PP se negara a apoyar\u00a0\u201cuna herramienta que ahora se est\u00e1\u00a0demostrando tan beneficiosa para la ciudad y que, adem\u00e1s, pone fin al modelo de urbanismo depredador&#8221;<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/07\/26-07-2024-El-PSPV-de-Castello-valora-el-efecto-dinamizador-del-Plan-General-en-la-economia-local.mp3\" autoplay><\/audio><figcaption class=\"wp-element-caption\">Declaraciones Jos\u00e9 Luis L\u00f3pez<\/figcaption><\/figure>\n\n\n\n<p>El portavoz adjunto del Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3, <strong>Jos\u00e9\u00a0Luis L\u00f3pez<\/strong>, ha puesto en valor la importancia del Plan General impulsado por el PSPV en la dinamizaci\u00f3n econ\u00f3mica de la ciudad.\u00a0\u201cEs una realidad que gracias al nuevo planeamiento urban\u00edstico y la seguridad jur\u00eddica que garantiza, Castell\u00f3\u00a0est\u00e1\u00a0atrayendo inversiones tras m\u00e1s de una d\u00e9cada de par\u00e1lisis por la anulaci\u00f3n judicial del antiguo ordenamiento del PP\u201d, destaca L\u00f3pez, quien ostent\u00f3 las responsabilidades del \u00e1rea de Urbanismo en el pasado mandato.<\/p>\n\n\n\n<p>En este sentido, el concejal socialista lamenta que <strong>Bego\u00f1a Carrasco<\/strong> se negara en la legislatura pasada a apoyar\u00a0\u201cuna herramienta que ahora se est\u00e1\u00a0demostrando tan beneficiosa para la ciudad y que, adem\u00e1s, pone fin al modelo de urbanismo depredador propio de\u00a0\u00e9pocas pasadas\u201d.\u00a0\u201cAfortunadamente el Plan General impulsado bajo el mandato socialista se hizo realidad pese a la negativa del PP y ahora Castell\u00f3 tiene uno de los ordenamientos m\u00e1s vanguardistas, el primero de un gran municipio aprobado con la LOTUP, que garantiza un crecimiento racional y sostenible\u201d, recuerda L\u00f3pez.<\/p>\n\n\n\n<p>Se\u00f1ala, adem\u00e1s, que&nbsp;\u201ctodas las voces expertas en el&nbsp;\u00e1mbito del urbanismo y la construcci\u00f3n de la ciudad han valorado positivamente esta herramienta de ordenaci\u00f3n que ahora est\u00e1&nbsp;posibilitando sacar adelante nuevos proyectos\u201d. \u201cUn crecimiento que contribuye a la generaci\u00f3n de empleo y a la actividad econ\u00f3mica local y que, por primera vez, ser\u00e1 ordenado y basado en par\u00e1metros de sostenibilidad\u201d, recalca el portavoz adjunto socialista.<\/p>\n\n\n\n<p><strong>Los tribunales avalan el Plan General<\/strong><br>Al contrario de lo ocurrido con el Plan General del PP, que fue anulado en los tribunales, la justicia ha avalado el ordenamiento impulsado por el PSPV en todos y cada uno de los recursos presentados. \u201cEs la clara muestra de un trabajo pol\u00edtico y t\u00e9cnico bien hecho, del planeamiento m\u00e1s democratizado y participado de la historia de esta ciudad, que contrasta con la mala gesti\u00f3n y la desidia de los gobiernos del PP que dejaron como legado una ciudad sin futuro y sin oportunidades de crecimiento\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25cf L\u00f3pez lamenta que el PP se negara a apoyar\u00a0\u201cuna herramienta que ahora se est\u00e1\u00a0demostrando tan beneficiosa para la ciudad y que, adem\u00e1s, pone fin al modelo de urbanismo depredador&#8221; El portavoz adjunto del Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3, Jos\u00e9\u00a0Luis L\u00f3pez, ha puesto en valor la importancia del Plan General impulsado por &#8230;<\/p>\n","protected":false},"author":48,"featured_media":3688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[85,448],"class_list":["post-5762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-jose-luis-lopez","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"\u25cf L\u00f3pez lamenta que el PP se negara a apoyar\u00a0\u201cuna herramienta que ahora se est\u00e1\u00a0demostrando tan beneficiosa para la ciudad y que, adem\u00e1s, pone fin al modelo de urbanismo depredador&#8221; El portavoz adjunto del Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3, Jos\u00e9\u00a0Luis L\u00f3pez, ha puesto en valor la importancia del Plan General impulsado por ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-26T11:04:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-26T11:19:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local\",\"datePublished\":\"2024-07-26T11:04:21+00:00\",\"dateModified\":\"2024-07-26T11:19:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/\"},\"wordCount\":416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"keywords\":[\"Jos\u00e9 Luis L\u00f3pez\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/\",\"name\":\"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"datePublished\":\"2024-07-26T11:04:21+00:00\",\"dateModified\":\"2024-07-26T11:19:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local - PSPV-PSOE CASTELL\u00d3","og_description":"\u25cf L\u00f3pez lamenta que el PP se negara a apoyar\u00a0\u201cuna herramienta que ahora se est\u00e1\u00a0demostrando tan beneficiosa para la ciudad y que, adem\u00e1s, pone fin al modelo de urbanismo depredador&#8221; El portavoz adjunto del Grupo Municipal Socialista en el Ayuntamiento de Castell\u00f3, Jos\u00e9\u00a0Luis L\u00f3pez, ha puesto en valor la importancia del Plan General impulsado por ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2024-07-26T11:04:21+00:00","article_modified_time":"2024-07-26T11:19:27+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local","datePublished":"2024-07-26T11:04:21+00:00","dateModified":"2024-07-26T11:19:27+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/"},"wordCount":416,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","keywords":["Jos\u00e9 Luis L\u00f3pez","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/","name":"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","datePublished":"2024-07-26T11:04:21+00:00","dateModified":"2024-07-26T11:19:27+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-de-castello-valora-el-efecto-dinamizador-del-plan-general-en-la-economia-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV de Castell\u00f3 valora el efecto dinamizador del Plan General\u00a0en la econom\u00eda local"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/5762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=5762"}],"version-history":[{"count":9,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/5762\/revisions"}],"predecessor-version":[{"id":5777,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/5762\/revisions\/5777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/3688"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=5762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=5762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=5762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}