{"id":4857,"date":"2024-05-11T12:42:17","date_gmt":"2024-05-11T10:42:17","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=4857"},"modified":"2024-06-19T11:12:57","modified_gmt":"2024-06-19T09:12:57","slug":"el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/","title":{"rendered":"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s&#8217;agilitze el projecte de construcci\u00f3 de l&#8217;institut"},"content":{"rendered":"\n<p>\u25cf <strong><em>El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, destaca que les pressions del PSPV i el rebuig de la comunitat educativa \u201chan perm\u00e9s que el PP, tant a l&#8217;ajuntament com en la Generalitat, facen marxa enrere en el seu intent de canviar el solar reservat per l\u2019Acord de Fadrell en el nou Pla General\u00bb<\/em><\/strong><\/p>\n\n\n\n<p>El Grup Municipal Socialista a l&#8217;Ajuntament de Castell\u00f3 ha destacat el canvi de postura del Partit Popular sobre el nou institut Cr\u00e8mor, \u201cperqu\u00e8 sembla que finalment renunciaran a canviar-lo d&#8217;ubicaci\u00f3 despr\u00e9s de la pressi\u00f3 tant del PSPV com de la comunitat educativa\u201d.<\/p>\n\n\n\n<p><strong>Jos\u00e9 Luis L\u00f3pez<\/strong>, portaveu adjunt socialista, considerava \u201cfora de lloc els moviments del Partit Popular, tant en el si de l&#8217;ajuntament com en la Generalitat, per a proposar un terreny de superf\u00edcie m\u00e9s xicoteta, no sabem amb quins interessos\u201d. Aix\u00f2 suposava \u201cun nou menyspreu del PP i Vox a les fam\u00edlies que estan pendents de la construcci\u00f3 de l&#8217;institut Cr\u00e8mor, \u201cplanificat i recollit en el Pla General que aprovem amb el govern de progr\u00e9s de l\u2019Acord de Fadrell que va liderar el Partit Socialista\u201d.<\/p>\n\n\n\n<p>Despr\u00e9s d&#8217;escoltar ara el portaveu de l&#8217;equip de govern, <strong>Vicent Sales<\/strong>, \u201cdir que finalment es mantindr\u00e0 el terreny ja aprovat per nosaltres, el que toca ara \u00e9s continuar fent passos en ferm perqu\u00e8 el nou institut Cr\u00e8mor siga una realitat al m\u00e9s prompte possible\u201d. En aquest sentit, des del Grup Socialista \u201creclamarem a <strong>Bego\u00f1a Carrasco<\/strong> que es pose les piles i pressione per a activar la redacci\u00f3 del projecte per a construir l&#8217;institut, ja siga instant a aix\u00f2 a la Conselleria d&#8217;Educaci\u00f3 o demanant la delegaci\u00f3 de compet\u00e8ncies a trav\u00e9s del Pla Edificant\u201d.<\/p>\n\n\n\n<p>L\u00f3pez recorda que \u201cestem parlant d&#8217;una demanda hist\u00f2rica de les fam\u00edlies per a donar resposta a la saturaci\u00f3 de l&#8217;IES Bovalar\u201d, reclamaci\u00f3 que va culminar amb la reserva d&#8217;uns terrenys consensuats amb la comunitat educativa\u201d. Des del govern de l\u2019Acord de Fadrell, liderat pel PSPV, \u201cens vam comprometre a reservar en el nou Pla General un s\u00f2l amb la superf\u00edcie necess\u00e0ria per a construir aquest institut, a m\u00e9s d&#8217;urbanitzar els terrenys confrontants de la ribera del Riu Sec per a millorar els accessos al futur institut\u201d.<\/p>\n\n\n\n<p>El portaveu adjunt del PSPV subratlla a m\u00e9s \u201cel nul inter\u00e9s de Carrasco per al\u00e7ar-li la veu al seu cap <strong>Maz\u00f3n<\/strong>, perqu\u00e8 ni tan sols va ser capa\u00e7 de presentar esmenes als pressupostos auton\u00f2mics, que van deixar en zero euros la partida per a construir l&#8217;institut Cr\u00e8mor\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25cf El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, destaca que les pressions del PSPV i el rebuig de la comunitat educativa \u201chan perm\u00e9s que el PP, tant a l&#8217;ajuntament com en la Generalitat, facen marxa enrere en el seu intent de canviar el solar reservat per l\u2019Acord de Fadrell en el nou &#8230;<\/p>\n","protected":false},"author":48,"featured_media":4750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[87],"class_list":["post-4857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms-va","tag-jose-luis-lopez-va"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s&#039;agilitze el projecte de construcci\u00f3 de l&#039;institut - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s&#039;agilitze el projecte de construcci\u00f3 de l&#039;institut - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"\u25cf El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, destaca que les pressions del PSPV i el rebuig de la comunitat educativa \u201chan perm\u00e9s que el PP, tant a l&#8217;ajuntament com en la Generalitat, facen marxa enrere en el seu intent de canviar el solar reservat per l\u2019Acord de Fadrell en el nou ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-11T10:42:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T09:12:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1064\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s&#8217;agilitze el projecte de construcci\u00f3 de l&#8217;institut\",\"datePublished\":\"2024-05-11T10:42:17+00:00\",\"dateModified\":\"2024-06-19T09:12:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/\"},\"wordCount\":469,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg\",\"keywords\":[\"Jos\u00e9 Luis L\u00f3pez\"],\"articleSection\":[\"Grup Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/\",\"name\":\"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s'agilitze el projecte de construcci\u00f3 de l'institut - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg\",\"datePublished\":\"2024-05-11T10:42:17+00:00\",\"dateModified\":\"2024-06-19T09:12:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg\",\"width\":1600,\"height\":1064},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s&#8217;agilitze el projecte de construcci\u00f3 de l&#8217;institut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s'agilitze el projecte de construcci\u00f3 de l'institut - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s'agilitze el projecte de construcci\u00f3 de l'institut - PSPV-PSOE CASTELL\u00d3","og_description":"\u25cf El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, destaca que les pressions del PSPV i el rebuig de la comunitat educativa \u201chan perm\u00e9s que el PP, tant a l&#8217;ajuntament com en la Generalitat, facen marxa enrere en el seu intent de canviar el solar reservat per l\u2019Acord de Fadrell en el nou ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2024-05-11T10:42:17+00:00","article_modified_time":"2024-06-19T09:12:57+00:00","og_image":[{"width":1600,"height":1064,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s&#8217;agilitze el projecte de construcci\u00f3 de l&#8217;institut","datePublished":"2024-05-11T10:42:17+00:00","dateModified":"2024-06-19T09:12:57+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/"},"wordCount":469,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg","keywords":["Jos\u00e9 Luis L\u00f3pez"],"articleSection":["Grup Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/","url":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/","name":"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s'agilitze el projecte de construcci\u00f3 de l'institut - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg","datePublished":"2024-05-11T10:42:17+00:00","dateModified":"2024-06-19T09:12:57+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg","width":1600,"height":1064},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/el-pspv-aplaudeix-el-canvi-de-posicio-del-pp-sobre-el-solar-del-futur-ies-cremor-de-castello-i-reclama-que-sagilitze-el-projecte-de-construccio-de-linstitut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV aplaudeix el canvi de posici\u00f3 del PP sobre el solar del futur IES Cr\u00e8mor\u00a0de Castell\u00f3\u00a0i reclama que s&#8217;agilitze el projecte de construcci\u00f3 de l&#8217;institut"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/04\/20240430-La-unica-aportacion-de-Begona-Carrasco-al-proyecto-logistico-del-Grau-es-un-video-y-un-nombre-porque-la-zona-industrial-la-diseno-el-Acord-de-Fadrell-en-el-Plan-General.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/4857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=4857"}],"version-history":[{"count":3,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/4857\/revisions"}],"predecessor-version":[{"id":4860,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/4857\/revisions\/4860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/4750"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=4857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=4857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=4857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}