{"id":3691,"date":"2024-01-17T13:56:05","date_gmt":"2024-01-17T12:56:05","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=3691"},"modified":"2024-06-19T11:18:23","modified_gmt":"2024-06-19T09:18:23","slug":"que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/","title":{"rendered":"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l&#8217;inexistent cas dels sobres, \u00e9s indecent&#8221;\u00a0"},"content":{"rendered":"\n<p><strong><em>El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, qualifica de \u201clamentables\u201d les declaracions de l&#8217;alcaldessa de Castell\u00f3, \u201cqui en lloc de respectar els procediments judicials pret\u00e9n ara donar lli\u00e7ons de dec\u00e8ncia pol\u00edtica, quan ella i els seus van portar fins al l\u00edmit un procediment que Fiscalia no va secundar\u201d<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Jos\u00e9 Luis L\u00f3pez assenyala que \u201cel que hauria de fer la senyora Carrasco \u00e9s posar-se al costat dels ve\u00efns i reclamar danys i perjudicis en la instrucci\u00f3 oberta en el Jutjat d&#8217;Instrucci\u00f3 4 de Castell\u00f3 per a investigar als autors de les pintades i adhesius contra el PSOE\u201d<\/em><\/strong><\/p>\n\n\n\n<p>El portaveu adjunt del Grup Municipal Socialista a l&#8217;Ajuntament de Castell\u00f3, Jos\u00e9 Luis L\u00f3pez, ha qualificat de \u201cindecents\u201d les declaracions de l&#8217;alcaldessa, Bego\u00f1a Carrasco, en acusar el PSPV-PSOE de \u2018fer oposici\u00f3 utilitzant la Just\u00edcia\u201d per sol\u00b7licitar que s&#8217;investigue a l&#8217;autor o autors de les pintades i adhesius contra el Partit Socialista durant l&#8217;any passat 2023, especialment en la campanya electoral del 28M.<\/p>\n\n\n\n<p>Per a L\u00f3pez, \u201cque la senyora Carrasco, eixa que va portar fins al l\u00edmit, ajunte els seus companys i companyes del Partit Popular, el cas inexistent dels sobres, demanant ni m\u00e9s ni menys que sis anys de pres\u00f3 contra Enric Nomded\u00e9u i Ali Brancal, acusament ara al PSOE de fer oposici\u00f3 a trav\u00e9s de la Just\u00edcia \u00e9s de vergonya\u201d.<\/p>\n\n\n\n<p>El regidor socialista subratlla que \u201csi hi ha alg\u00fa no pot donar lli\u00e7ons en aquest sentit \u00e9s la senyora Carrasco i el PP, que es van inventar un cas inexistent, capa\u00e7os d&#8217;anar en contra dels propis criteris de la Fiscalia i generant un mal irreparable als representants pol\u00edtics als quals va acusar sense cap prova\u201d. En aquesta l\u00ednia, considera que \u201cel m\u00ednim que se li pot demanar a la m\u00e0xima representant de l&#8217;Ajuntament de Castell\u00f3 \u00e9s que respecte als jutges i jutgesses i, a m\u00e9s, que defense els interessos municipals\u201d.<\/p>\n\n\n\n<p>Sobre aquest tema, Jos\u00e9 Luis L\u00f3pez ha recordat que el Jutjat d&#8217;Instrucci\u00f3 4 de Castell\u00f3, l&#8217;encarregat d&#8217;obrir dilig\u00e8ncies per a determinar als responsables de la campanya difamat\u00f2ria, \u201cha animat a l&#8217;ajuntament a personar-se ja que, com a afectat pels danys en el mobiliari urb\u00e0 i propietats municipals, el normal \u00e9s que vulga con\u00e9ixer als responsables i actuar\u201d. Malgrat aix\u00f2, \u201cen data de hui la senyora alcaldessa prefereix tancar l&#8217;orella i no defensar el patrimoni de tots els ve\u00efns i ve\u00efnes de Castell\u00f3\u201d.<\/p>\n\n\n\n<p>L\u00f3pez subratlla que \u201cni Carrasco ni ning\u00fa pot enlletgir al Partit Socialista que es vulga buscar als culpables de difamar al PSOE, de danyar el mobiliari urb\u00e0 de la ciutat i d&#8217;embrutar els nostres carrers\u201d. \u00c9s m\u00e9s, \u201cl&#8217;adequat en aquests casos \u00e9s que l&#8217;alcaldessa recolzara el dret de tots els partits pol\u00edtics a defensar-se enfront d&#8217;aquestes campanya d&#8217;odi i crispaci\u00f3 i no mirar a un altre costat\u201d.<\/p>\n\n\n\n<p><strong>Ratificaci\u00f3 de la den\u00fancia<\/strong><br>En la seua qualitat de secretari d&#8217;Organitzaci\u00f3 del PSPV de Castell\u00f3 Jos\u00e9 Luis L\u00f3pez, acompanyat per l\u2019exalcaldesa i candidata al maig de 2023 a l&#8217;alcaldia, Amparo Marco, va assistir el dilluns al Jutjat d&#8217;Instrucci\u00f3 4 de Castell\u00f3, on estava citat per a ratificar la den\u00fancia per les pintades i la identificaci\u00f3 d&#8217;una furgoneta al costat d&#8217;unes pintades en una rotonda d&#8217;acc\u00e9s a la ciutat.<\/p>\n\n\n\n<p>Tal com va explicar L\u00f3pez en eixir del jutjat, \u201cla principal novetat va ser con\u00e9ixer que l&#8217;atestat aportat per la Policia Nacional recull que el contracte de lloguer del citat vehicle est\u00e0 signat pel senyor Cristian Ram\u00edrez, actual regidor de Mobilitat amb Bego\u00f1a Carrasco al capdavant de l&#8217;ajuntament i en aquella \u00e8poca membre de la candidatura del PP a les eleccions municipals\u201d. A m\u00e9s, l&#8217;atestat policial contempla documentaci\u00f3 en la qual queda determinat que el contracte de lloguer de la furgoneta, encara que signat per Cristian Ram\u00edrez, est\u00e0 a nom del Partit Popular de Castell\u00f3.<\/p>\n\n\n\n<p>Des del PSPV \u201ccontinuarem defensant l&#8217;honor del Partit Socialista i arribarem fins on h\u00e0gem d&#8217;arribar de la m\u00e0 de la Just\u00edcia i de la Policia Nacional perqu\u00e8 s&#8217;investigue tota eixa campanya de difamaci\u00f3 i que els culpables responguen davant la Just\u00edcia\u201d, recalca L\u00f3pez.<\/p>\n\n\n\n<p>En la seua den\u00fancia del 5 de maig de 2023 davant la Policia Nacional, el PSPV-PSOE de Castell\u00f3 va traslladar l&#8217;aparici\u00f3 de pintades en diferents punts de la ciutat, amb pintades i missatges amb textos com \u201cCORRUPSOE 5%\u201d i \u201cGOLPSOE DE ESTADO\u201d. D&#8217;igual manera es va informar de la pres\u00e8ncia de desenes d&#8217;adhesius amb el mateix contingut sobre el mobiliari urb\u00e0.<\/p>\n\n\n\n<p><strong>Ampliaci\u00f3 de la den\u00fancia<\/strong><br>Amb posterioritat, el 22 de maig Jos\u00e9 Luis L\u00f3pez va ampliar el contingut de la den\u00fancia, dilig\u00e8ncia en la qual informava de la localitzaci\u00f3, amb data 18 de maig, d&#8217;una furgoneta estacionada al costat d&#8217;una rotonda dels accessos a Castell\u00f3 per l&#8217;eixida sud de l&#8217;autopista. Al costat del vehicle, del qual es va aportar la matr\u00edcula, hi havia un home amb la cara tapada, a m\u00e9s d&#8217;observar-se una segona persona en el seu interior. La den\u00fancia, a m\u00e9s, va ser traslladada pel PSPV eixe mateix 22 de maig a la Fiscalia Provincial de Castell\u00f3, sent el 4 de juny de 2023 quan es va comunicar la incoaci\u00f3 de procediment penal, que \u00e9s el que ara es troba en procediment de dilig\u00e8ncies pr\u00e8vies per part del Jutjat d&#8217;Instrucci\u00f3 4 de Castell\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, qualifica de \u201clamentables\u201d les declaracions de l&#8217;alcaldessa de Castell\u00f3, \u201cqui en lloc de respectar els procediments judicials pret\u00e9n ara donar lli\u00e7ons de dec\u00e8ncia pol\u00edtica, quan ella i els seus van portar fins al l\u00edmit un procediment que Fiscalia no va secundar\u201d Jos\u00e9 Luis L\u00f3pez assenyala &#8230;<\/p>\n","protected":false},"author":48,"featured_media":3688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[72,22],"tags":[277,87],"class_list":["post-3691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agrupacio-municipal-va","category-gms-va","tag-amparo-marco-va","tag-jose-luis-lopez-va"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l&#039;inexistent cas dels sobres, \u00e9s indecent&quot;\u00a0 - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l&#039;inexistent cas dels sobres, \u00e9s indecent&quot;\u00a0 - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, qualifica de \u201clamentables\u201d les declaracions de l&#8217;alcaldessa de Castell\u00f3, \u201cqui en lloc de respectar els procediments judicials pret\u00e9n ara donar lli\u00e7ons de dec\u00e8ncia pol\u00edtica, quan ella i els seus van portar fins al l\u00edmit un procediment que Fiscalia no va secundar\u201d Jos\u00e9 Luis L\u00f3pez assenyala ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-17T12:56:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T09:18:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l&#8217;inexistent cas dels sobres, \u00e9s indecent&#8221;\u00a0\",\"datePublished\":\"2024-01-17T12:56:05+00:00\",\"dateModified\":\"2024-06-19T09:18:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/\"},\"wordCount\":942,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"keywords\":[\"Amparo Marco\",\"Jos\u00e9 Luis L\u00f3pez\"],\"articleSection\":[\"Agrupaci\u00f3 Municipal\",\"Grup Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/\",\"name\":\"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l'inexistent cas dels sobres, \u00e9s indecent\\\"\u00a0 - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"datePublished\":\"2024-01-17T12:56:05+00:00\",\"dateModified\":\"2024-06-19T09:18:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l&#8217;inexistent cas dels sobres, \u00e9s indecent\u00bb\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l'inexistent cas dels sobres, \u00e9s indecent\"\u00a0 - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l'inexistent cas dels sobres, \u00e9s indecent\"\u00a0 - PSPV-PSOE CASTELL\u00d3","og_description":"El portaveu adjunt del Grup Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, qualifica de \u201clamentables\u201d les declaracions de l&#8217;alcaldessa de Castell\u00f3, \u201cqui en lloc de respectar els procediments judicials pret\u00e9n ara donar lli\u00e7ons de dec\u00e8ncia pol\u00edtica, quan ella i els seus van portar fins al l\u00edmit un procediment que Fiscalia no va secundar\u201d Jos\u00e9 Luis L\u00f3pez assenyala ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2024-01-17T12:56:05+00:00","article_modified_time":"2024-06-19T09:18:23+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l&#8217;inexistent cas dels sobres, \u00e9s indecent&#8221;\u00a0","datePublished":"2024-01-17T12:56:05+00:00","dateModified":"2024-06-19T09:18:23+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/"},"wordCount":942,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","keywords":["Amparo Marco","Jos\u00e9 Luis L\u00f3pez"],"articleSection":["Agrupaci\u00f3 Municipal","Grup Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/","url":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/","name":"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l'inexistent cas dels sobres, \u00e9s indecent\"\u00a0 - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","datePublished":"2024-01-17T12:56:05+00:00","dateModified":"2024-06-19T09:18:23+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/va\/que-begona-carrasco-acuse-el-pspv-de-fer-oposicio-utilitzant-la-justicia-despres-que-el-pp-demanara-6-anys-de-preso-a-nomdedeu-i-brancal-per-linexistent-cas-dels-sobres-es-indecent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"\u201cQue Bego\u00f1a Carrasco acuse el PSPV de fer oposici\u00f3 utilitzant la Just\u00edcia, despr\u00e9s que el PP demanara 6 anys de pres\u00f3 a Nomded\u00e9u i Brancal per l&#8217;inexistent cas dels sobres, \u00e9s indecent\u00bb\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240117-Que-Begona-Carrasco-acuse-al-PSPV-de-hacer-oposicion-utilizando-la-Justicia-despues-de-que-el-PP-pidiese-6-anos-de-carcel.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/3691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=3691"}],"version-history":[{"count":4,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/3691\/revisions"}],"predecessor-version":[{"id":3973,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/3691\/revisions\/3973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/3688"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=3691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=3691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=3691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}