{"id":3649,"date":"2024-01-12T17:21:16","date_gmt":"2024-01-12T16:21:16","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=3649"},"modified":"2024-02-12T09:47:52","modified_gmt":"2024-02-12T08:47:52","slug":"el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/","title":{"rendered":"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal"},"content":{"rendered":"\n<p><em><strong>El portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, denuncia la modificaci\u00f3n de la plaza de t\u00e9cnico de protocolo y organizaci\u00f3n de eventos, a la que quitan la necesidad de ser especialista en Relaciones Internacionales, \u201cpara hacerle un traje a medida a alguien\u201d<\/strong><\/em><\/p>\n\n\n\n<p>El primer presupuesto elaborado por Bego\u00f1a Carrasco al frente del Ayuntamiento de Castell\u00f3 \u201cviene ya con la marca de la derecha y la ultraderecha en su habitual desmantelamiento de los servicios sociales, como ha venido demostrando el Partido Popular cada vez que ha gobernado, y m\u00e1s ahora que est\u00e1 rendido por completo a las tesis m\u00e1s ultras de Vox\u201d.<\/p>\n\n\n\n<p>El \u00faltimo de los ejemplos, seg\u00fan el portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, aparece en la propuesta de plantilla de personal del consistorio castellonense para el a\u00f1o 2024, impulsada por el teniente de alcalde popular Juan Carlos Redondo, donde aparece \u201cla amortizaci\u00f3n de varios puestos de trabajo, en la que nos encontramos de forma lamentable con la supresi\u00f3n de dos plazas de Int\u00e9rprete de Lengua de Signos del grupo B, una de ellas a media jornada\u201d.<\/p>\n\n\n\n<p>Para L\u00f3pez, \u201cdecisiones como estas reflejan la ideolog\u00eda de quien gobierna, siempre recortando en iniciativas sociales que repercuten en colectivos que luchan a diario por la mejora de servicios de la administraci\u00f3n p\u00fablica\u201d. Un ejemplo fue en anteriores crisis econ\u00f3micas, \u201cdonde el Partido Popular se ceb\u00f3 en temas sociales que hab\u00edan supuesto un gran logro, como era la teleasistencia\u201d. Seg\u00fan el edil socialista, \u201caunque no nos sorprenda esta forma de actuar, habitual de la derecha, no deja de ser escandalosa, porque tener que crear nuevas plazas en la plantilla del ayuntamiento a costa de suprimir dos de int\u00e9rpretes de Lengua de Signos es para hac\u00e9rselo mirar\u201d.<\/p>\n\n\n\n<p><strong>Protocolo<\/strong><br>Otra de las \u201cllamativas\u201d amortizaciones en el apartado de la plantilla es el de la plaza \u2018T\u00e9cnico\/a de relaciones Internacionales y Protocolo\u2019, que eliminan para crear el puesto de trabajo \u2018T\u00e9cnico de Protocolo y Organizaci\u00f3n de Eventos\u2019. Para el portavoz adjunto socialista, \u201ces como poco llamativo que se desprendan del logro que era disponer de un responsable de protocolo formado en Relaciones Internacionales, con dominio de idiomas, y ahora se le quite importancia a un aspecto clave para cualquier instituci\u00f3n en Europa\u201d. Por ello,\u201dmucho nos tememos que este paso que ha dado la alcaldesa de la ciudad, en lugar de mirar por la imagen de Castell\u00f3, lo haga para hacerle un traje a medida a alguien\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, denuncia la modificaci\u00f3n de la plaza de t\u00e9cnico de protocolo y organizaci\u00f3n de eventos, a la que quitan la necesidad de ser especialista en Relaciones Internacionales, \u201cpara hacerle un traje a medida a alguien\u201d El primer presupuesto elaborado por Bego\u00f1a Carrasco al frente del Ayuntamiento &#8230;<\/p>\n","protected":false},"author":48,"featured_media":3650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[85],"class_list":["post-3649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-jose-luis-lopez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, denuncia la modificaci\u00f3n de la plaza de t\u00e9cnico de protocolo y organizaci\u00f3n de eventos, a la que quitan la necesidad de ser especialista en Relaciones Internacionales, \u201cpara hacerle un traje a medida a alguien\u201d El primer presupuesto elaborado por Bego\u00f1a Carrasco al frente del Ayuntamiento ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-12T16:21:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-12T08:47:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal\",\"datePublished\":\"2024-01-12T16:21:16+00:00\",\"dateModified\":\"2024-02-12T08:47:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/\"},\"wordCount\":461,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg\",\"keywords\":[\"Jos\u00e9 Luis L\u00f3pez\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/\",\"name\":\"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg\",\"datePublished\":\"2024-01-12T16:21:16+00:00\",\"dateModified\":\"2024-02-12T08:47:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/","og_locale":"es_ES","og_type":"article","og_title":"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal - PSPV-PSOE CASTELL\u00d3","og_description":"El portavoz adjunto del Grupo Municipal Socialista, Jos\u00e9 Luis L\u00f3pez, denuncia la modificaci\u00f3n de la plaza de t\u00e9cnico de protocolo y organizaci\u00f3n de eventos, a la que quitan la necesidad de ser especialista en Relaciones Internacionales, \u201cpara hacerle un traje a medida a alguien\u201d El primer presupuesto elaborado por Bego\u00f1a Carrasco al frente del Ayuntamiento ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2024-01-12T16:21:16+00:00","article_modified_time":"2024-02-12T08:47:52+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal","datePublished":"2024-01-12T16:21:16+00:00","dateModified":"2024-02-12T08:47:52+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/"},"wordCount":461,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg","keywords":["Jos\u00e9 Luis L\u00f3pez"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/","name":"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg","datePublished":"2024-01-12T16:21:16+00:00","dateModified":"2024-02-12T08:47:52+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pp-y-vox-desmantelan-nuevos-servicios-sociales-en-el-ayuntamiento-de-castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PP y Vox desmantelan nuevos servicios sociales en el Ayuntamiento de Castell\u00f3 al amortizar dos plazas de int\u00e9rpretes de lengua de signos de la plantilla de personal"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2024\/01\/20240112-El-PP-y-Vox-desmantelan-nuevos-servicios-sociales-en-el-Ayuntamiento-de-Castello-al-amortizar-dos-plazas-de-interpretes-de-lengua-de-signos-de-la-plantilla-de-personal.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/3649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=3649"}],"version-history":[{"count":3,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/3649\/revisions"}],"predecessor-version":[{"id":3983,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/3649\/revisions\/3983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/3650"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=3649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=3649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=3649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}