{"id":11626,"date":"2026-07-15T17:40:29","date_gmt":"2026-07-15T15:40:29","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=11626"},"modified":"2026-07-15T17:40:30","modified_gmt":"2026-07-15T15:40:30","slug":"el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/","title":{"rendered":"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>El Grupo Municipal Socialista traslada al ayuntamiento nuevas quejas vecinales por calles que no se limpian, parcelas con riesgo de incendio y vertidos ilegales &#8220;sin que Bego\u00f1a Carrasco, preocupada \u00fanicamente por el centro, quiera darse por enterada&#8221;<\/em><\/li>\n<\/ul>\n\n\n\n<p>El Grupo Municipal Socialista ha denunciado el continuo abandono que sufren los barrios de Castell\u00f3 mientras el gobierno de <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a> \u201csolo se preocupa por destinar recursos para mantener cuidada la plaza Mayor de la ciudad\u201d. El PSPV ha trasladado esta semana a las comisiones municipales nuevas incidencias comunicadas por el vecindario \u201cque evidencian la falta de limpieza y mantenimiento en distintos puntos del t\u00e9rmino municipal\u201d.<\/p>\n\n\n\n<p>Entre las reclamaciones presentadas, como se\u00f1ala la concejala <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/anun-lainez\/\">Anunciaci\u00f3n L\u00e1inez<\/a>, figuran una calle del grupo San Bartolom\u00e9, en la cuadra Borriolench, que no se limpia porque ni siquiera aparece en el plano de trabajo de la empresa concesionaria; un solar invadido por maleza junto a la calle Mosqueruela, que supone un riesgo potencial de incendio para las viviendas colindantes; la acumulaci\u00f3n de escombros y decenas de neum\u00e1ticos en la zona del camino Mestrets, junto al R\u00edo Seco y el cementerio de San Jos\u00e9, y un nuevo vertedero incontrolado en el Cam\u00ed la Fileta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1067\" height=\"800\" data-attachment-id=\"11629\" data-permalink=\"https:\/\/agrupacionespsoe.es\/castello\/20260715-el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello-2-2\/\" data-orig-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited.jpeg\" data-orig-size=\"1067,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"20260715 &#8211; El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3 2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited-300x225.jpeg\" data-large-file=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited-1024x768.jpeg\" src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited.jpeg\" alt=\"\" class=\"wp-image-11629\" srcset=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited.jpeg 1067w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited-300x225.jpeg 300w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited-1024x768.jpeg 1024w, https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello-2-edited-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1067px) 100vw, 1067px\" \/><\/figure>\n\n\n\n<p>Desde el PSPV lamentan que &#8220;mientras Carrasco se preocupa por las fotos, los actos y el escaparate del centro, los barrios acumulan basura, maleza y vertederos ilegales sin que el ayuntamiento act\u00fae&#8221;. Los socialistas recuerdan que estas situaciones no son casos aislados, sino el reflejo de una gesti\u00f3n que &#8220;ha olvidado a buena parte de la ciudad&#8221;.<\/p>\n\n\n\n<p>Por ello, el Grupo Municipal Socialista exige al gobierno municipal que atienda de manera inmediata estas reclamaciones vecinales y garantice un servicio de limpieza y mantenimiento digno en todos los barrios de Castell\u00f3, &#8220;porque todos los vecinos y vecinas pagan sus impuestos y tienen el mismo derecho a vivir en una ciudad limpia y cuidada, vivan donde vivan&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal Socialista ha denunciado el continuo abandono que sufren los barrios de Castell\u00f3 mientras el gobierno de Bego\u00f1a Carrasco \u201csolo se preocupa por destinar recursos para mantener cuidada la plaza Mayor de la ciudad\u201d. El PSPV ha trasladado esta semana a las comisiones municipales nuevas incidencias comunicadas por el vecindario \u201cque evidencian la &#8230;<\/p>\n","protected":false},"author":48,"featured_media":11627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33,1178],"tags":[95,733,448],"class_list":["post-11626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","category-urbanismo","tag-anun-lainez","tag-begona-carrasco","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3 - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3 - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El Grupo Municipal Socialista ha denunciado el continuo abandono que sufren los barrios de Castell\u00f3 mientras el gobierno de Bego\u00f1a Carrasco \u201csolo se preocupa por destinar recursos para mantener cuidada la plaza Mayor de la ciudad\u201d. El PSPV ha trasladado esta semana a las comisiones municipales nuevas incidencias comunicadas por el vecindario \u201cque evidencian la ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T15:40:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T15:40:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3\",\"datePublished\":\"2026-07-15T15:40:29+00:00\",\"dateModified\":\"2026-07-15T15:40:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/\"},\"wordCount\":336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg\",\"keywords\":[\"Anun L\u00e1inez\",\"Bego\u00f1a Carrasco\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\",\"Urbanismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/\",\"name\":\"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3 - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg\",\"datePublished\":\"2026-07-15T15:40:29+00:00\",\"dateModified\":\"2026-07-15T15:40:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3 - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3 - PSPV-PSOE CASTELL\u00d3","og_description":"El Grupo Municipal Socialista ha denunciado el continuo abandono que sufren los barrios de Castell\u00f3 mientras el gobierno de Bego\u00f1a Carrasco \u201csolo se preocupa por destinar recursos para mantener cuidada la plaza Mayor de la ciudad\u201d. El PSPV ha trasladado esta semana a las comisiones municipales nuevas incidencias comunicadas por el vecindario \u201cque evidencian la ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2026-07-15T15:40:29+00:00","article_modified_time":"2026-07-15T15:40:30+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3","datePublished":"2026-07-15T15:40:29+00:00","dateModified":"2026-07-15T15:40:30+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/"},"wordCount":336,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg","keywords":["Anun L\u00e1inez","Bego\u00f1a Carrasco","Todos"],"articleSection":["Grupo Municipal Socialista","Urbanismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/","name":"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3 - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg","datePublished":"2026-07-15T15:40:29+00:00","dateModified":"2026-07-15T15:40:30+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-castello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV denuncia solares abandonados, basuras y vertederos incontrolados en los barrios de Castell\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260715-El-PSPV-denuncia-solares-abandonados-basuras-y-vertederos-incontrolados-en-los-barrios-de-Castello.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/11626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=11626"}],"version-history":[{"count":3,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/11626\/revisions"}],"predecessor-version":[{"id":11632,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/11626\/revisions\/11632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/11627"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=11626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=11626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=11626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}