{"id":11554,"date":"2026-06-11T09:51:43","date_gmt":"2026-06-11T07:51:43","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=11554"},"modified":"2026-07-06T09:54:15","modified_gmt":"2026-07-06T07:54:15","slug":"el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/","title":{"rendered":"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>Patricia Puerta lamenta que, pese al compromiso municipal de tener listo el operativo de playas en junio, las zonas adaptadas siguen sin servicios b\u00e1sicos para garantizar el acceso de las personas con discapacidad<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260611-El-PSPV-denuncia-que-Begona-Carrasco-vuelve-a-abandonar-las-playas-accesibles-de-Castello-un-ano-despues-de-las-mismas-denuncias.mp3\" autoplay><\/audio><\/figure>\n\n\n\n<p>La portavoz del Grupo Municipal Socialista, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>, ha denunciado el \u201cnuevo fracaso\u201d del gobierno de <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Bego\u00f1a Carrasco<\/a> en la puesta a punto de las playas accesibles de Castell\u00f3 y ha criticado que, un a\u00f1o despu\u00e9s de las denuncias realizadas por el PSPV, la situaci\u00f3n vuelva a repetirse en los mismos t\u00e9rminos.<\/p>\n\n\n\n<p>Puerta ha recordado que el verano pasado los socialistas ya alertaron del estado de abandono de los espacios adaptados del litoral castellonense, con pasarelas en mal estado, ba\u00f1os y vestuarios cerrados, falta de personal especializado y ausencia de servicios b\u00e1sicos para las personas con discapacidad.<\/p>\n\n\n\n<p>\u201cDoce meses despu\u00e9s comprobamos que el gobierno municipal no ha aprendido absolutamente nada. Estamos ya casi a mitad de junio y las playas accesibles siguen sin ofrecer unas condiciones dignas para garantizar que todas las personas puedan disfrutar del litoral en igualdad de condiciones\u201d, ha se\u00f1alado.<\/p>\n\n\n\n<p>La portavoz socialista ha recordado que la propia alcaldesa, Bego\u00f1a Carrasco, anunci\u00f3 hace semanas que el operativo de playas estar\u00eda completamente preparado en junio. Pese a ello, numerosas zonas adaptadas contin\u00faan sin toldos, sin ba\u00f1os accesibles, sin cambiadores, sin mobiliario espec\u00edfico y sin personal especializado de atenci\u00f3n al ba\u00f1o. A ello se suman pasarelas cubiertas de arena sin mantenimiento, flexipasarelas que ni siquiera llegan hasta la orilla y barandillas instaladas en el agua que dificultan la accesibilidad al encontrarse desalineadas respecto a los itinerarios adaptados.<\/p>\n\n\n\n<p>Adem\u00e1s, Puerta ha advertido de la inexistencia de mecanismos efectivos de control para garantizar que los espacios reservados para personas con discapacidad sean utilizados realmente por quienes los necesitan, una situaci\u00f3n que acaba generando nuevas barreras para quienes deber\u00edan ser los principales beneficiarios de estas instalaciones. \u201cLo m\u00e1s grave es que no estamos hablando de problemas sobrevenidos ni de cuestiones imprevistas. Son exactamente las mismas deficiencias que denunciamos el a\u00f1o pasado y que hemos vuelto a trasladar durante meses en los consejos rectores y \u00f3rganos municipales. El gobierno de Carrasco conoc\u00eda perfectamente la situaci\u00f3n y ha decidido no actuar\u201d, ha afirmado.<\/p>\n\n\n\n<p>Para la portavoz socialista, este nuevo incumplimiento demuestra que la pol\u00edtica tur\u00edstica del actual gobierno municipal \u201cest\u00e1 basada en la imagen y no en la gesti\u00f3n\u201d. A su juicio, \u201cestamos ante un nuevo ejemplo del modelo Carrasco: muchas fotograf\u00edas, muchos anuncios y mucha propaganda, pero muy poco trabajo detr\u00e1s. Las playas accesibles no pueden convertirse en un decorado para hacerse una foto al inicio del verano mientras las personas con discapacidad siguen encontrando obst\u00e1culos para acceder al mar\u201d, ha se\u00f1alado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La portavoz del Grupo Municipal Socialista, Patricia Puerta, ha denunciado el \u201cnuevo fracaso\u201d del gobierno de Bego\u00f1a Carrasco en la puesta a punto de las playas accesibles de Castell\u00f3 y ha criticado que, un a\u00f1o despu\u00e9s de las denuncias realizadas por el PSPV, la situaci\u00f3n vuelva a repetirse en los mismos t\u00e9rminos. Puerta ha recordado &#8230;<\/p>\n","protected":false},"author":48,"featured_media":11495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1186,33],"tags":[733,81,448],"class_list":["post-11554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienestar-social","category-gms","tag-begona-carrasco","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"La portavoz del Grupo Municipal Socialista, Patricia Puerta, ha denunciado el \u201cnuevo fracaso\u201d del gobierno de Bego\u00f1a Carrasco en la puesta a punto de las playas accesibles de Castell\u00f3 y ha criticado que, un a\u00f1o despu\u00e9s de las denuncias realizadas por el PSPV, la situaci\u00f3n vuelva a repetirse en los mismos t\u00e9rminos. Puerta ha recordado ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-11T07:51:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T07:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"1294\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias\",\"datePublished\":\"2026-06-11T07:51:43+00:00\",\"dateModified\":\"2026-07-06T07:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/\"},\"wordCount\":497,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg\",\"keywords\":[\"Bego\u00f1a Carrasco\",\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Bienestar social\",\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/\",\"name\":\"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg\",\"datePublished\":\"2026-06-11T07:51:43+00:00\",\"dateModified\":\"2026-07-06T07:54:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg\",\"width\":1320,\"height\":1294},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias - PSPV-PSOE CASTELL\u00d3","og_description":"La portavoz del Grupo Municipal Socialista, Patricia Puerta, ha denunciado el \u201cnuevo fracaso\u201d del gobierno de Bego\u00f1a Carrasco en la puesta a punto de las playas accesibles de Castell\u00f3 y ha criticado que, un a\u00f1o despu\u00e9s de las denuncias realizadas por el PSPV, la situaci\u00f3n vuelva a repetirse en los mismos t\u00e9rminos. Puerta ha recordado ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2026-06-11T07:51:43+00:00","article_modified_time":"2026-07-06T07:54:15+00:00","og_image":[{"width":1320,"height":1294,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias","datePublished":"2026-06-11T07:51:43+00:00","dateModified":"2026-07-06T07:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/"},"wordCount":497,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg","keywords":["Bego\u00f1a Carrasco","Patricia Puerta","Todos"],"articleSection":["Bienestar social","Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/","name":"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg","datePublished":"2026-06-11T07:51:43+00:00","dateModified":"2026-07-06T07:54:15+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg","width":1320,"height":1294},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-denuncia-que-begona-carrasco-vuelve-a-abandonar-las-playas-accesibles-de-castello-un-ano-despues-de-las-mismas-denuncias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV denuncia que Bego\u00f1a Carrasco vuelve a abandonar las playas accesibles de Castell\u00f3 un a\u00f1o despu\u00e9s de las mismas denuncias"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2026\/07\/20260704-El-PSPV-denuncia-nuevas-deficiencias-en-las-playas-accesibles-de-Castello-y-acusa-a-Carrasco-de-enganar-a-la-ciudadania-con-su-continua-propaganda-1.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/11554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=11554"}],"version-history":[{"count":2,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/11554\/revisions"}],"predecessor-version":[{"id":11557,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/11554\/revisions\/11557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/11495"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=11554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=11554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=11554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}