{"id":10006,"date":"2025-12-23T12:26:02","date_gmt":"2025-12-23T11:26:02","guid":{"rendered":"https:\/\/agrupacionespsoe.es\/castello\/?p=10006"},"modified":"2026-03-24T08:55:32","modified_gmt":"2026-03-24T07:55:32","slug":"el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco","status":"publish","type":"post","link":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/","title":{"rendered":"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>La portavoz del Grupo Municipal Socialista, Patricia Puerta, asegura que el gobierno de la derecha va a incrementar el total de impuestos y tasas en 14,5 millones respecto al \u00faltimo presupuesto del Acord de Fadrell de 2023<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>El Partido Socialista lamenta el rechazo a sus 82 enmiendas, \u201cporque eran la llave para paliar el abandono de Bego\u00f1a Carrasco en temas clave de la ciudad como la vivienda, la movilidad sostenible, la limpieza, la atenci\u00f3n a los barrios, la igualdad o los colectivos sociales\u201d<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/3nkApU4LasE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>El Grupo Municipal Socialista ha votado hoy en contra de los presupuestos para 2026 del gobierno de PP y Vox \u201cporque estamos de nuevo ante unas cuentas ficticias, plagadas de enga\u00f1os, que abandonan \u00e1reas clave como la vivienda, la sostenibilidad y los servicios sociales y porque, de nuevo, ratifican el aumento de la presi\u00f3n fiscal a los castellonenses y reafirma el impacto en el bolsillo de la ciudadan\u00eda a consecuencia del \u2018Basurazo de <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/begona-carrasco\/\">Carrasco<\/a>\u2019\u201d.<\/p>\n\n\n\n<p><a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/patricia-puerta\/\">Patricia Puerta<\/a>, portavoz socialista, ha recordado las promesas de la alcaldesa en el debate de los anteriores presupuestos, donde dijo que en 2025 bajar\u00eda los impuestos en 2 millones de euros. \u201cY la realidad es que esta promesa ha sido una gran mentira, porque vamos a cerrar este a\u00f1o recaudando 8 millones m\u00e1s entre tasas e impuestos municipales, que por cierto no sabemos d\u00f3nde han ido a parar\u201d.<\/p>\n\n\n\n<p>Para el presupuesto de 2026 la alcaldesa, el pasado 3 de diciembre, \u201clleg\u00f3 a decir que se va a mitigar el efecto de su \u2018basurazo\u2019, pero si nos ce\u00f1imos a los impuestos, tasas y precios p\u00fablicos exclusivamente municipales, en 2026 van a recaudar 712.000 euros m\u00e1s que en 2025\u201d. Y si se compara este dato con el \u00faltimo presupuesto del Acord de Fadrell de 2023, el PP va a incrementar el total de impuestos y tasas en 14,5 millones.<\/p>\n\n\n\n<p>\u201cLa realidad es que, desde que gobierna la se\u00f1ora Carrasco, los vecinos y vecinas de Castell\u00f3 sufren una mayor presi\u00f3n fiscal\u201d, ha subrayado Puerta. Y a eso se a\u00f1ade que \u201cnada de estos 14,5 millones de euros van destinados ni a vivienda, ni a empleo, ni a bienestar social, ni a incrementar la limpieza o el mantenimiento de los barrios de nuestra ciudad, que es lo que realmente le preocupa a la ciudadan\u00eda\u201d.<\/p>\n\n\n\n<p>De forma paralela, \u201ccomo parece que no tienen suficiente con el dinero que recaudan de aumentar la presi\u00f3n fiscal a la ciudadan\u00eda, vuelve la vieja escuela del PP de aumentar la deuda\u201d. Al respecto, ha recordado que el PSPV se encontr\u00f3 en 2015 con una deuda de 82,2 millones, cifra que se rebaj\u00f3 hasta los 30 millones en 2023. \u201cAhora, vuelven a endeudarse con otro pr\u00e9stamo y la previsi\u00f3n de deuda a largo plazo, para el cierre de 2026, ya estar\u00e1 en casi 55 millones de euros\u201d, ha comentado la portavoz socialista, quien acusa a PP y Vox de poner en peligro la estabilidad financiera de este ayuntamiento \u201ca costa de despilfarros en saraos\u201d.<\/p>\n\n\n\n<p><strong>Vivienda<\/strong><\/p>\n\n\n\n<p>Uno de los aspectos \u201cm\u00e1s sonrojantes\u201d es el de la vivienda. \u201cParece que, para la alcaldesa, hablar de la legislatura de la vivienda es abrir partidas para ayudas al alquiler social, para los j\u00f3venes, para invertir en vivienda social y para rehabilitaci\u00f3n que, en conjunto, suman 44.000 euros\u201d. Para Patricia Puerta, \u201cm\u00e1s que apostar por la vivienda se apuesta por burlarse de las y los castellonenses\u201d.<\/p>\n\n\n\n<p>Otro aspecto negativo de las cuentas municipales para 2026 es la eliminaci\u00f3n de las ayudas para el fomento de empleo, adem\u00e1s de penalizar a las entidades sociales, pymes y aut\u00f3nomos al no permitirles que se presenten a m\u00e1s de dos convocatorias. \u201cLa forma de gestionar de la se\u00f1ora Carrasco est\u00e1 provocando que decenas de proyectos de empleo, la mayor\u00eda destinados a las personas m\u00e1s vulnerables, no podr\u00e1n ejecutarse, lo que supone cerrar las puertas a la inserci\u00f3n en el mercado laboral a muchas familias de nuestra ciudad\u201d.<\/p>\n\n\n\n<p>Frente a esta \u201cnefasta gesti\u00f3n,\u201d desde el Grupo Municipal Socialista se han presentado un total de 82 enmiendas por valor de 9,2 millones de euros. Enmiendas que son fruto del di\u00e1logo con la ciudadan\u00eda y con colectivos sociales de nuestra ciudad.<\/p>\n\n\n\n<p>En materia de vivienda, desde el Partido Socialista se han presentado varias propuestas por valor de 2,5 millones de euros para ayudas al alquiler, adquisici\u00f3n de vivienda social y rehabilitaci\u00f3n de viviendas municipales. Adem\u00e1s, se crea una nueva partida de 500.000\u20ac para ayudas a la rehabilitaci\u00f3n y accesibilidad de viviendas de m\u00e1s de 50 a\u00f1os.<\/p>\n\n\n\n<p><strong>Abandono de los barrios<\/strong><\/p>\n\n\n\n<p>Los presupuestos de PP y Vox, para el Partido Socialista, \u201cviven alejados de la realidad que viven las vecinas y vecinos de los barrios de Castell\u00f3, pues la ciudad es algo m\u00e1s que la plaza Mayor\u201d. \u201cPara pagar impuestos son de primera, pero para recibir atenci\u00f3n del gobierno de la derecha y la ultraderecha, son de segunda\u201d, se ha lamentado la portavoz socialista. Por eso, desde el PSPV se han propuesto varias iniciativas para atender las necesidades de los barrios, que han sido rechazadas por el PP.<\/p>\n\n\n\n<p>Entre ellas, crear una nueva partida para un plan de choque de limpieza en todos los distritos con 300.000\u20ac. \u201cSabemos que la se\u00f1ora Carrasco no pisa los barrios de esta ciudad, pero al menos podr\u00eda atender los mensajes que deja la ciudadan\u00eda en sus redes sociales, quej\u00e1ndose del abandono que sufren todos ellos y de la acumulaci\u00f3n de suciedad, basuras y vertederos incontrolados\u201d. Para Puerta, \u201cresponder y asumir errores se llama humildad, pero ocultar las cr\u00edticas en las redes, o incluso atacar a los vecinos y vecinas, que es lo que hace la alcaldesa, se llama soberbia\u201d.<\/p>\n\n\n\n<p><strong>Negacionista clim\u00e1tica<\/strong><\/p>\n\n\n\n<p>Del total de nuestras 82 enmiendas socialistas, 27 de ellas se refer\u00edan a propuestas para el a\u00f1o que viene que el gobierno PP-Vox ha dejado a cero euros, muchas de ellas centradas en la movilidad urbana y en el medio ambiente. Y es que, como ha expuesto Patricia Puerta, \u201clos hechos nos demuestran lo que ya hemos ido advirtiendo todos estos meses: que tenemos a una negacionista clim\u00e1tica a los mandos del ayuntamiento, no porque est\u00e9 secuestrada por sus socios ultras, sino porque sencillamente se ha mimetizado con ellos. Para la sra. alcaldesa no existe la amenaza clim\u00e1tica, y el centro de la ciudad tiene que volver a ser para los coches, no para el disfrute del peat\u00f3n\u201d.<\/p>\n\n\n\n<p>\u2018<strong>Basurazo de Carrasco\u2019<\/strong><\/p>\n\n\n\n<p>El presupuesto de 2026 \u201cmuestra tambi\u00e9n que PP y Vox no tienen intenci\u00f3n de mejorar su gesti\u00f3n de las basuras\u201d. Para el a\u00f1o que viene la alcaldesa \u201cha reservado la impresionante cifra de 100 euros en una asistencia t\u00e9cnica para mejorar la implantaci\u00f3n de la tasa de basura, lo que demuestra su nula preocupaci\u00f3n por rebajar el impacto del Basurazo de Carrasco en 2026 y 2027\u201d. A ello se une \u201cla inexistencia\u201d de una partida para adquirir contenedores inteligentes, clave para apostar por el reciclaje y bonificar m\u00e1s a los que m\u00e1s se implican.<\/p>\n\n\n\n<p>Los colectivos sociales son otra de las prioridades del PSPV, porque \u201cha quedado claro que al gobierno de PP y Vox le molesta trabajar en defensa de las personas m\u00e1s vulnerables\u201d. De ah\u00ed que se hayan presentado 40 enmiendas para aumentar un 8% tanto las subvenciones nominativas como las de concurrencia competitiva destinadas a proyectos sociales desarrollados por ONG\u2019s y a proyectos en materia de igualdad.<\/p>\n\n\n\n<p>\u2018<strong>El sueldazo de Carrasco\u2019<\/strong><\/p>\n\n\n\n<p>El resumen de las cuentas municipales para 2026 es \u201cconfirmar que PP y Vox no tienen un modelo de ciudad y que a la alcaldesa solo le preocupa salir bien en las fotos de postureo y, por cierto, seguir imparable con la subida de su sueldo anual, porque esta es tambi\u00e9n otra tomadura de pelo a la ciudadan\u00eda\u201d.<\/p>\n\n\n\n<p>Al respecto, la portavoz socialista ha animado a los vecinos y vecinas de Castell\u00f3 a entrar en la web municipal, \u201cdonde podr\u00e1n acceder a las retribuciones de la actual corporaci\u00f3n\u201d. Y ah\u00ed se puede comprobar que \u201ca la se\u00f1ora Carrasco, esa que dijo que se bajaba el sueldo, se le olvid\u00f3 confesarle a la ciudadan\u00eda que todas las subidas de sueldo que se aprobasen para el personal funcionario, tambi\u00e9n las aplicar\u00eda a la corporaci\u00f3n, a diferencia de lo que hicimos desde el Acord de Fadrell, que apost\u00f3 por congelar los sueldos de las y los pol\u00edticos durante los 4 a\u00f1os de mandato\u201d.<\/p>\n\n\n\n<p>La realidad \u201ces que, cuando finalice este mandato, la se\u00f1ora Bego\u00f1a Carrasco habr\u00e1 percibido como alcaldesa unos 5.000 \u20ac m\u00e1s que su predecesora, <a href=\"https:\/\/agrupacionespsoe.es\/castello\/tag\/amparo-marco\/\">Amparo Marco<\/a>, por lo que entendemos que salga sonriente en sus fotos de post\u00edn mientras recorta fondos a los colectivos sociales, igualdad y sostenibilidad\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal Socialista ha votado hoy en contra de los presupuestos para 2026 del gobierno de PP y Vox \u201cporque estamos de nuevo ante unas cuentas ficticias, plagadas de enga\u00f1os, que abandonan \u00e1reas clave como la vivienda, la sostenibilidad y los servicios sociales y porque, de nuevo, ratifican el aumento de la presi\u00f3n fiscal &#8230;<\/p>\n","protected":false},"author":48,"featured_media":10011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[275,1151,733,81,448],"class_list":["post-10006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gms","tag-amparo-marco","tag-basurazo","tag-begona-carrasco","tag-patricia-puerta","tag-todos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"og:description\" content=\"El Grupo Municipal Socialista ha votado hoy en contra de los presupuestos para 2026 del gobierno de PP y Vox \u201cporque estamos de nuevo ante unas cuentas ficticias, plagadas de enga\u00f1os, que abandonan \u00e1reas clave como la vivienda, la sostenibilidad y los servicios sociales y porque, de nuevo, ratifican el aumento de la presi\u00f3n fiscal ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/\" \/>\n<meta property=\"og:site_name\" content=\"PSPV-PSOE CASTELL\u00d3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pspv.castellodelaplana\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-23T11:26:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T07:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1254\" \/>\n\t<meta property=\"og:image:height\" content=\"831\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castello1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:site\" content=\"@pspv_cs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"castello1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/\"},\"author\":{\"name\":\"castello1\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\"},\"headline\":\"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019\",\"datePublished\":\"2025-12-23T11:26:02+00:00\",\"dateModified\":\"2026-03-24T07:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/\"},\"wordCount\":1496,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg\",\"keywords\":[\"Amparo Marco\",\"Basurazo\",\"Bego\u00f1a Carrasco\",\"Patricia Puerta\",\"Todos\"],\"articleSection\":[\"Grupo Municipal Socialista\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/\",\"name\":\"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3\",\"isPartOf\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg\",\"datePublished\":\"2025-12-23T11:26:02+00:00\",\"dateModified\":\"2026-03-24T07:55:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg\",\"width\":1254,\"height\":831},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/agrupacionespsoe.es\/castello\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#website\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"name\":\"PSPV-PSOE CASTELL\u00d3\",\"description\":\"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3\",\"publisher\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#organization\",\"name\":\"PSPV-PSOE Castell\u00f3\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"contentUrl\":\"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg\",\"width\":2500,\"height\":2500,\"caption\":\"PSPV-PSOE Castell\u00f3\"},\"image\":{\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pspv.castellodelaplana\",\"https:\/\/x.com\/pspv_cs\",\"https:\/\/www.instagram.com\/pspvpsoecastello\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a\",\"name\":\"castello1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g\",\"caption\":\"castello1\"},\"url\":\"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/","og_locale":"es_ES","og_type":"article","og_title":"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3","og_description":"El Grupo Municipal Socialista ha votado hoy en contra de los presupuestos para 2026 del gobierno de PP y Vox \u201cporque estamos de nuevo ante unas cuentas ficticias, plagadas de enga\u00f1os, que abandonan \u00e1reas clave como la vivienda, la sostenibilidad y los servicios sociales y porque, de nuevo, ratifican el aumento de la presi\u00f3n fiscal ...","og_url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/","og_site_name":"PSPV-PSOE CASTELL\u00d3","article_publisher":"https:\/\/www.facebook.com\/pspv.castellodelaplana","article_published_time":"2025-12-23T11:26:02+00:00","article_modified_time":"2026-03-24T07:55:32+00:00","og_image":[{"width":1254,"height":831,"url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg","type":"image\/jpeg"}],"author":"castello1","twitter_card":"summary_large_image","twitter_creator":"@pspv_cs","twitter_site":"@pspv_cs","twitter_misc":{"Escrito por":"castello1","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#article","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/"},"author":{"name":"castello1","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a"},"headline":"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019","datePublished":"2025-12-23T11:26:02+00:00","dateModified":"2026-03-24T07:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/"},"wordCount":1496,"commentCount":0,"publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg","keywords":["Amparo Marco","Basurazo","Bego\u00f1a Carrasco","Patricia Puerta","Todos"],"articleSection":["Grupo Municipal Socialista"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/","url":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/","name":"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019 - PSPV-PSOE CASTELL\u00d3","isPartOf":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg","datePublished":"2025-12-23T11:26:02+00:00","dateModified":"2026-03-24T07:55:32+00:00","breadcrumb":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#primaryimage","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg","width":1254,"height":831},{"@type":"BreadcrumbList","@id":"https:\/\/agrupacionespsoe.es\/castello\/el-pspv-vota-en-contra-del-presupuesto-del-engano-del-pp-y-vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-basurazo-de-carrasco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupacionespsoe.es\/castello\/"},{"@type":"ListItem","position":2,"name":"El PSPV vota en contra del presupuesto del \u2018enga\u00f1o\u2019 del PP y Vox al abandonar la vivienda, derrochar en propaganda y mantener el \u2018Basurazo de Carrasco\u2019"}]},{"@type":"WebSite","@id":"https:\/\/agrupacionespsoe.es\/castello\/#website","url":"https:\/\/agrupacionespsoe.es\/castello\/","name":"PSPV-PSOE CASTELL\u00d3","description":"PSPV-PSOE | Agrupaci\u00f3 de Castell\u00f3","publisher":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupacionespsoe.es\/castello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agrupacionespsoe.es\/castello\/#organization","name":"PSPV-PSOE Castell\u00f3","url":"https:\/\/agrupacionespsoe.es\/castello\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/","url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","contentUrl":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2023\/04\/PORTADA-PSOE-CASTELLO.jpg","width":2500,"height":2500,"caption":"PSPV-PSOE Castell\u00f3"},"image":{"@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pspv.castellodelaplana","https:\/\/x.com\/pspv_cs","https:\/\/www.instagram.com\/pspvpsoecastello\/"]},{"@type":"Person","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/f3bc5b2f9dc6a399e9e98596ae24a20a","name":"castello1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agrupacionespsoe.es\/castello\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f1da428d6479d1127419c0b58796865?s=96&d=mm&r=g","caption":"castello1"},"url":"https:\/\/agrupacionespsoe.es\/castello\/author\/castello1\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/agrupacionespsoe.es\/castello\/wp-content\/uploads\/sites\/45\/2025\/12\/20251223-El-PSPV-vota-en-contra-del-presupuesto-del-\u2018engano-del-PP-y-Vox-al-abandonar-la-vivienda-derrochar-en-propaganda-y-mantener-el-\u2018Basurazo-de-Carrasco.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/10006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/comments?post=10006"}],"version-history":[{"count":11,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/10006\/revisions"}],"predecessor-version":[{"id":10018,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/posts\/10006\/revisions\/10018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media\/10011"}],"wp:attachment":[{"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/media?parent=10006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/categories?post=10006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupacionespsoe.es\/castello\/wp-json\/wp\/v2\/tags?post=10006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}